{"id":14545,"date":"2025-12-10T13:00:00","date_gmt":"2025-12-10T12:00:00","guid":{"rendered":"https:\/\/www.salvador-dali.org\/?post_type=noticia&#038;p=14545"},"modified":"2025-12-10T10:17:11","modified_gmt":"2025-12-10T09:17:11","slug":"la-fundacio-dali-anuncia-un-programa-internacional-de-beques-de-recerca","status":"publish","type":"noticia","link":"https:\/\/www.salvador-dali.org\/ca\/fundacio-dali\/noticia\/la-fundacio-dali-anuncia-un-programa-internacional-de-beques-de-recerca\/","title":{"rendered":"La Fundaci\u00f3 Dal\u00ed anuncia un programa internacional de beques de recerca"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Figueres, 10 de desembre de 2025.- <\/strong>La Fundaci\u00f3 Gala-Salvador Dal\u00ed anuncia l\u2019obertura de la convocat\u00f2ria 2026 del <strong><em>Dal\u00ed Fellowship Programme<\/em><\/strong>, un programa internacional de beques i investigaci\u00f3 destinat a impulsar l\u2019estudi, la reflexi\u00f3 i el coneixement al voltant de l\u2019obra, el pensament i el llegat de Salvador Dal\u00ed.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"629\" src=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/07\/5068_editora_84_8_1_1024.jpg\" alt=\"La incondicionalidad surrealista de Salvador Dal\u00ed a debate\" class=\"wp-image-13150\" srcset=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/07\/5068_editora_84_8_1_1024.jpg 500w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/07\/5068_editora_84_8_1_1024-238x300.jpg 238w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><figcaption class=\"wp-element-caption\">Foto Eric Schaal. Salvador Dal\u00ed escrivint <em>La vida secreta de Salvador Dal\u00ed<\/em> a casa de Caresse Crosby, Hampton Manor, Virg\u00ednia,1941.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Un programa per a investigadors i estudiosos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;edici\u00f3 2026 ofereix <strong>dues beques individuals<\/strong>, adre\u00e7ades a investigadors i estudiosos que vulguin desenvolupar projectes originals en \u00e0mbits afins a la figura de Dal\u00ed. Es valoraran especialment treballs en els camps seg\u00fcents:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Dal\u00ed, arquitectura i escenografia<\/li>\n\n\n\n<li>Dal\u00ed performatiu<\/li>\n\n\n\n<li>Dal\u00ed i la ci\u00e8ncia<\/li>\n\n\n\n<li>Dal\u00ed i la cultura material<\/li>\n\n\n\n<li>Dal\u00ed i la moda<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Ressons de Dal\u00ed en l&#8217;art contemporani<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cada beca tindr\u00e0 una durada de <strong>sis mesos<\/strong> amb una dotaci\u00f3 econ\u00f2mica de <strong>18.000 euros.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Comissi\u00f3 d&#8217;Avaluaci\u00f3 i Seguiment estar\u00e0 presidida per Estrella de Diego, Catedr\u00e0tica d&#8217;Art Contemporani de la Universitat Complutense de Madrid i membre del Patronat de la Fundaci\u00f3 Gala-Salvador Dal\u00ed.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Un entorn \u00fanic per a la recerca<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El programa \u00e9s residencial. Les persones seleccionades tindran l&#8217;oportunitat de fer la recerca en un entorn excepcional: la seu de la Fundaci\u00f3 Dal\u00ed a Figueres, al costat del Teatre-Museu Dal\u00ed. A m\u00e9s, tindran, entre d\u2019altres avantatges, facilitats especials en l&#8217;\u00fas dels recursos i les bases de dades documentals, bibliogr\u00e0fics i digitals de la Fundaci\u00f3, un seguiment tutoritzat per part d&#8217;una persona especialitzada de la Fundaci\u00f3 propera a l&#8217;\u00e0mbit del projecte, un espai de treball a la seu de la Fundaci\u00f3, aix\u00ed com facilitats d&#8217;allotjament.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Atracci\u00f3 de talent nacional i internacional<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El <strong><em>Dal\u00ed Fellowship Programme<\/em><\/strong> cerca atraure talent investigador, enfortir les aliances amb universitats i institucions a nivell nacional i internacional, i consolidar la Fundaci\u00f3 com un referent cultural global, fomentant nous enfocaments sobre la figura de Salvador Dal\u00ed i el seu impacte en les Belles Arts, la cultura i el pensament contemporani.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per aix\u00f2, la Fundaci\u00f3 Dal\u00ed s&#8217;ha posat en contacte amb m\u00e9s de 100 institucions universit\u00e0ries, de recerca i muse\u00edstiques, tant nacionals com internacionals, amb l&#8217;objectiu d&#8217;atreure talent i afavorir la recepci\u00f3 i la transfer\u00e8ncia de coneixement a trav\u00e9s d&#8217;investigadors i especialistes de prestigi internacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Programa s&#8217;emmarca en el prop\u00f2sit de la Fundaci\u00f3 de facilitar a les generacions presents i futures una visi\u00f3 hol\u00edstica de la vida mitjan\u00e7ant el coneixement i el gaudi de l&#8217;art, situant l&#8217;obra i l&#8217;univers dalini\u00e0 com a eix d&#8217;enriquiment personal i cultural.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Per a m\u00e9s informaci\u00f3<\/strong>:<br>Oficina de Premsa<br>Imma Parada<br>Tel. 687416709<br><a href=\"mailto:comunicacio@fundaciodali.org\">comunicacio@fundaciodali.org<\/a> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Fundaci\u00f3 Gala-Salvador Dal\u00ed anuncia l\u2019obertura de la convocat\u00f2ria 2026 del Dal\u00ed Fellowship Programme<\/p>\n","protected":false},"featured_media":13150,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false,"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":""},"categoria-actualitat":[],"class_list":["post-14545","noticia","type-noticia","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Fundaci\u00f3 Dal\u00ed anuncia un programa internacional de beques de recerca - Fundaci\u00f3 Gala - Salvador Dal\u00ed<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salvador-dali.org\/ca\/fundacio-dali\/noticia\/la-fundacio-dali-anuncia-un-programa-internacional-de-beques-de-recerca\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Fundaci\u00f3 Dal\u00ed anuncia un programa internacional de beques de recerca - Fundaci\u00f3 Gala - Salvador Dal\u00ed\" \/>\n<meta property=\"og:description\" content=\"La Fundaci\u00f3 Gala-Salvador Dal\u00ed anuncia l\u2019obertura de la convocat\u00f2ria 2026 del Dal\u00ed Fellowship Programme\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salvador-dali.org\/ca\/fundacio-dali\/noticia\/la-fundacio-dali-anuncia-un-programa-internacional-de-beques-de-recerca\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3 Gala - Salvador Dal\u00ed\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MuseusDali\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/07\/5068_editora_84_8_1_1024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"629\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MuseuDali\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/ca\\\/fundacio-dali\\\/noticia\\\/la-fundacio-dali-anuncia-un-programa-internacional-de-beques-de-recerca\\\/\",\"url\":\"https:\\\/\\\/www.salvador-dali.org\\\/ca\\\/fundacio-dali\\\/noticia\\\/la-fundacio-dali-anuncia-un-programa-internacional-de-beques-de-recerca\\\/\",\"name\":\"La Fundaci\u00f3 Dal\u00ed anuncia un programa internacional de beques de recerca - Fundaci\u00f3 Gala - Salvador Dal\u00ed\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/ca\\\/fundacio-dali\\\/noticia\\\/la-fundacio-dali-anuncia-un-programa-internacional-de-beques-de-recerca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/ca\\\/fundacio-dali\\\/noticia\\\/la-fundacio-dali-anuncia-un-programa-internacional-de-beques-de-recerca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salvador-dali.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/5068_editora_84_8_1_1024.jpg\",\"datePublished\":\"2025-12-10T12:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/ca\\\/fundacio-dali\\\/noticia\\\/la-fundacio-dali-anuncia-un-programa-internacional-de-beques-de-recerca\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.salvador-dali.org\\\/ca\\\/fundacio-dali\\\/noticia\\\/la-fundacio-dali-anuncia-un-programa-internacional-de-beques-de-recerca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/ca\\\/fundacio-dali\\\/noticia\\\/la-fundacio-dali-anuncia-un-programa-internacional-de-beques-de-recerca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.salvador-dali.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/5068_editora_84_8_1_1024.jpg\",\"contentUrl\":\"https:\\\/\\\/www.salvador-dali.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/5068_editora_84_8_1_1024.jpg\",\"width\":500,\"height\":629,\"caption\":\"Foto Eric Schaal. Salvador Dal\u00ed escrivint La vida secreta de Salvador Dal\u00ed a casa de Caresse Crosby, Hampton Manor, Virg\u00ednia,1941.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/ca\\\/fundacio-dali\\\/noticia\\\/la-fundacio-dali-anuncia-un-programa-internacional-de-beques-de-recerca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.salvador-dali.org\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Fundaci\u00f3 Dal\u00ed anuncia un programa internacional de beques de recerca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.salvador-dali.org\\\/ca\\\/\",\"name\":\"Fundaci\u00f3 Gala - Salvador Dal\u00ed\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salvador-dali.org\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/ca\\\/#organization\",\"name\":\"Fundaci\u00f3 Gala - Salvador Dal\u00ed\",\"url\":\"https:\\\/\\\/www.salvador-dali.org\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.salvador-dali.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/fundacio-gala-salvador-dali.png\",\"contentUrl\":\"https:\\\/\\\/www.salvador-dali.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/fundacio-gala-salvador-dali.png\",\"width\":240,\"height\":240,\"caption\":\"Fundaci\u00f3 Gala - Salvador Dal\u00ed\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MuseusDali\",\"https:\\\/\\\/x.com\\\/MuseuDali\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/FundacioDali\",\"https:\\\/\\\/www.flickr.com\\\/fundacio_dali\\\/\",\"https:\\\/\\\/instagram.com\\\/museudali\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Fundaci\u00f3 Dal\u00ed anuncia un programa internacional de beques de recerca - Fundaci\u00f3 Gala - Salvador Dal\u00ed","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salvador-dali.org\/ca\/fundacio-dali\/noticia\/la-fundacio-dali-anuncia-un-programa-internacional-de-beques-de-recerca\/","og_locale":"ca_ES","og_type":"article","og_title":"La Fundaci\u00f3 Dal\u00ed anuncia un programa internacional de beques de recerca - Fundaci\u00f3 Gala - Salvador Dal\u00ed","og_description":"La Fundaci\u00f3 Gala-Salvador Dal\u00ed anuncia l\u2019obertura de la convocat\u00f2ria 2026 del Dal\u00ed Fellowship Programme","og_url":"https:\/\/www.salvador-dali.org\/ca\/fundacio-dali\/noticia\/la-fundacio-dali-anuncia-un-programa-internacional-de-beques-de-recerca\/","og_site_name":"Fundaci\u00f3 Gala - Salvador Dal\u00ed","article_publisher":"https:\/\/www.facebook.com\/MuseusDali","og_image":[{"width":500,"height":629,"url":"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/07\/5068_editora_84_8_1_1024.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MuseuDali","twitter_misc":{"Temps estimat de lectura":"3 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.salvador-dali.org\/ca\/fundacio-dali\/noticia\/la-fundacio-dali-anuncia-un-programa-internacional-de-beques-de-recerca\/","url":"https:\/\/www.salvador-dali.org\/ca\/fundacio-dali\/noticia\/la-fundacio-dali-anuncia-un-programa-internacional-de-beques-de-recerca\/","name":"La Fundaci\u00f3 Dal\u00ed anuncia un programa internacional de beques de recerca - Fundaci\u00f3 Gala - Salvador Dal\u00ed","isPartOf":{"@id":"https:\/\/www.salvador-dali.org\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salvador-dali.org\/ca\/fundacio-dali\/noticia\/la-fundacio-dali-anuncia-un-programa-internacional-de-beques-de-recerca\/#primaryimage"},"image":{"@id":"https:\/\/www.salvador-dali.org\/ca\/fundacio-dali\/noticia\/la-fundacio-dali-anuncia-un-programa-internacional-de-beques-de-recerca\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/07\/5068_editora_84_8_1_1024.jpg","datePublished":"2025-12-10T12:00:00+00:00","breadcrumb":{"@id":"https:\/\/www.salvador-dali.org\/ca\/fundacio-dali\/noticia\/la-fundacio-dali-anuncia-un-programa-internacional-de-beques-de-recerca\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salvador-dali.org\/ca\/fundacio-dali\/noticia\/la-fundacio-dali-anuncia-un-programa-internacional-de-beques-de-recerca\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.salvador-dali.org\/ca\/fundacio-dali\/noticia\/la-fundacio-dali-anuncia-un-programa-internacional-de-beques-de-recerca\/#primaryimage","url":"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/07\/5068_editora_84_8_1_1024.jpg","contentUrl":"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/07\/5068_editora_84_8_1_1024.jpg","width":500,"height":629,"caption":"Foto Eric Schaal. Salvador Dal\u00ed escrivint La vida secreta de Salvador Dal\u00ed a casa de Caresse Crosby, Hampton Manor, Virg\u00ednia,1941."},{"@type":"BreadcrumbList","@id":"https:\/\/www.salvador-dali.org\/ca\/fundacio-dali\/noticia\/la-fundacio-dali-anuncia-un-programa-internacional-de-beques-de-recerca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.salvador-dali.org\/ca\/"},{"@type":"ListItem","position":2,"name":"La Fundaci\u00f3 Dal\u00ed anuncia un programa internacional de beques de recerca"}]},{"@type":"WebSite","@id":"https:\/\/www.salvador-dali.org\/ca\/#website","url":"https:\/\/www.salvador-dali.org\/ca\/","name":"Fundaci\u00f3 Gala - Salvador Dal\u00ed","description":"","publisher":{"@id":"https:\/\/www.salvador-dali.org\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salvador-dali.org\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.salvador-dali.org\/ca\/#organization","name":"Fundaci\u00f3 Gala - Salvador Dal\u00ed","url":"https:\/\/www.salvador-dali.org\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.salvador-dali.org\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/04\/fundacio-gala-salvador-dali.png","contentUrl":"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/04\/fundacio-gala-salvador-dali.png","width":240,"height":240,"caption":"Fundaci\u00f3 Gala - Salvador Dal\u00ed"},"image":{"@id":"https:\/\/www.salvador-dali.org\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MuseusDali","https:\/\/x.com\/MuseuDali","https:\/\/www.youtube.com\/user\/FundacioDali","https:\/\/www.flickr.com\/fundacio_dali\/","https:\/\/instagram.com\/museudali"]}]}},"_links":{"self":[{"href":"https:\/\/www.salvador-dali.org\/ca\/wp-json\/wp\/v2\/noticia\/14545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salvador-dali.org\/ca\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/www.salvador-dali.org\/ca\/wp-json\/wp\/v2\/types\/noticia"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salvador-dali.org\/ca\/wp-json\/wp\/v2\/media\/13150"}],"wp:attachment":[{"href":"https:\/\/www.salvador-dali.org\/ca\/wp-json\/wp\/v2\/media?parent=14545"}],"wp:term":[{"taxonomy":"categoria-actualitat","embeddable":true,"href":"https:\/\/www.salvador-dali.org\/ca\/wp-json\/wp\/v2\/categoria-actualitat?post=14545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}