{"id":99,"date":"2024-12-18T18:35:11","date_gmt":"2024-12-18T16:35:11","guid":{"rendered":"https:\/\/www.salvador-dali.org\/?page_id=99"},"modified":"2025-05-08T16:55:17","modified_gmt":"2025-05-08T14:55:17","slug":"activitats","status":"publish","type":"page","link":"https:\/\/www.salvador-dali.org\/ca\/educacio-i-activitats\/activitats\/","title":{"rendered":"Activitats"},"content":{"rendered":"\n<div class=\"wp-block-columns facetwp-filters is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Lloc<\/p>\n\n\n<div class=\"facetwp-facet facetwp-facet-activitat_lloc facetwp-type-fselect\" data-name=\"activitat_lloc\" data-type=\"fselect\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Idiomes<\/p>\n\n\n<div class=\"facetwp-facet facetwp-facet-activitat_idioma facetwp-type-fselect\" data-name=\"activitat_idioma\" data-type=\"fselect\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Idiomes<\/p>\n\n\n<div class=\"facetwp-facet facetwp-facet-activitat_dates_activitat facetwp-type-date_range\" data-name=\"activitat_dates_activitat\" data-type=\"date_range\"><\/div>\n<\/div>\n<\/div>\n\n\n<div class=\"facetwp-template\" data-name=\"activitats\"><ul class=\"fwpl-layout list\">\n  \t<li class=\"grid-item\">\n\n        \t\t\n        <div class=\"item-header\">\n            <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"245\" height=\"300\" src=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/08\/default2-245x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Salvador Dal\u00ed i Dom\u00e8nech, Eclipsi i osmosis vegetal, 1934 \u00a9 Salvador Dal\u00ed, Fundaci\u00f3 Gala-Salvador Dal\u00ed, Figueres, 2026\" srcset=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/08\/default2-245x300.jpg 245w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/08\/default2-768x940.jpg 768w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/08\/default2.jpg 800w\" sizes=\"auto, (max-width: 245px) 100vw, 245px\" \/><\/figure>\n\n            <div class=\"item-location\">\n            Castell Gala Dal\u00ed            <\/div>\n\n            \n\n            \n\n        <\/div>\n        <div class=\"item-content\">\n\n                        <a href=\"https:\/\/www.salvador-dali.org\/ca\/educacio-i-activitats\/activitat\/eclipsi-al-castell\/\"><div class=\"title\">Eclipsi al Castell<\/div><\/a>\n            <div class=\"item-data\">\n            12 d&#039;agost de 2026 a les 19:00            <\/div>\n            <div class=\"excerpt\">Aquest 12 d'agost, el Castell Gala Dal\u00ed de P\u00fabol amplia excepcionalment el seu horari fins a les 21 h perqu\u00e8 puguis gaudir d'una experi\u00e8ncia \u00fanica.<\/div>\n        <\/div>\n\t\t\n\t<\/li>\n\t\n  \t<li class=\"grid-item\">\n\n        \t\t\n        <div class=\"item-header\">\n            <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"210\" height=\"300\" src=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/07\/la-femme-visible_imatge-titol2-210x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/07\/la-femme-visible_imatge-titol2-210x300.jpg 210w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/07\/la-femme-visible_imatge-titol2-718x1024.jpg 718w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/07\/la-femme-visible_imatge-titol2-768x1096.jpg 768w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/07\/la-femme-visible_imatge-titol2-1077x1536.jpg 1077w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/07\/la-femme-visible_imatge-titol2.jpg 1402w\" sizes=\"auto, (max-width: 210px) 100vw, 210px\" \/><\/figure>\n\n            <div class=\"item-location\">\n            Castell Gala Dal\u00ed            <\/div>\n\n            \n\n            \n\n        <\/div>\n        <div class=\"item-content\">\n\n                        <a href=\"https:\/\/www.salvador-dali.org\/ca\/educacio-i-activitats\/activitat\/celebrant-gala-2026\/\"><div class=\"title\">Celebrant Gala 2026: La Femme Visible<\/div><\/a>\n            <div class=\"item-data\">\n            26 d&#039;agost de 2026 a les 19:00            <\/div>\n            <div class=\"excerpt\">La Femme Visible \/ La Dona Visible<\/div>\n        <\/div>\n\t\t\n\t<\/li>\n\t\n  \t<li class=\"grid-item\">\n\n        \t\t\n        <div class=\"item-header\">\n            <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/06\/\u00a9-Steph-Watson-Fotografia-2025-21-300x200.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/06\/\u00a9-Steph-Watson-Fotografia-2025-21-300x200.png 300w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/06\/\u00a9-Steph-Watson-Fotografia-2025-21-1024x682.png 1024w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/06\/\u00a9-Steph-Watson-Fotografia-2025-21-768x511.png 768w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/06\/\u00a9-Steph-Watson-Fotografia-2025-21.png 1205w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n            <div class=\"item-location\">\n            Castell Gala Dal\u00ed            <\/div>\n\n            \n\n            \n\n        <\/div>\n        <div class=\"item-content\">\n\n                        <a href=\"https:\/\/www.salvador-dali.org\/ca\/educacio-i-activitats\/activitat\/stage-fotografic-al-castell-gala-dali\/\"><div class=\"title\">Stage fotogr\u00e0fic al Castell Gala Dal\u00ed<\/div><\/a>\n            <div class=\"item-data\">\n            17, 18 i 19 de setembre de 2026            <\/div>\n            <div class=\"excerpt\">L'Escola Universit\u00e0ria de les Arts ERAM, juntament amb la Fundaci\u00f3 Gala - Salvador Dal\u00ed, proposen tres dies d'immersi\u00f3 en l'univers po\u00e8tic i simb\u00f2lic de Gala i Dal\u00ed<\/div>\n        <\/div>\n\t\t\n\t<\/li>\n\t\n  \t<li class=\"grid-item\">\n\n        \t\t\n        <div class=\"item-header\">\n            <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"189\" height=\"300\" src=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/05\/cartaobertaasalvadordali-189x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/05\/cartaobertaasalvadordali-189x300.jpg 189w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/05\/cartaobertaasalvadordali-644x1024.jpg 644w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/05\/cartaobertaasalvadordali.jpg 755w\" sizes=\"auto, (max-width: 189px) 100vw, 189px\" \/><\/figure>\n\n            <div class=\"item-location\">\n            Castell Gala Dal\u00ed            <\/div>\n\n            \n\n            \n\n        <\/div>\n        <div class=\"item-content\">\n\n                        <a href=\"https:\/\/www.salvador-dali.org\/ca\/educacio-i-activitats\/activitat\/carta-oberta-salvador-dali\/\"><div class=\"title\">Presentaci\u00f3 del llibre \u00abCarta oberta a Salvador Dal\u00ed\u00bb a P\u00fabol<\/div><\/a>\n            <div class=\"item-data\">\n            Divendres, 12 de juny de 2026a les 19:15            <\/div>\n            <div class=\"excerpt\">Una obra plena d\u2019ironia, provocaci\u00f3 i reflexions sobre l\u2019art, la societat i la seva pr\u00f2pia figura p\u00fablica. <\/div>\n        <\/div>\n\t\t\n\t<\/li>\n\t\n  \t<li class=\"grid-item\">\n\n        \t\t\n        <div class=\"item-header\">\n            <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/05\/Muntatge-Ioga-i-Celo-Pubol-300x200.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/05\/Muntatge-Ioga-i-Celo-Pubol-300x200.png 300w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/05\/Muntatge-Ioga-i-Celo-Pubol-1024x683.png 1024w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/05\/Muntatge-Ioga-i-Celo-Pubol-768x512.png 768w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/05\/Muntatge-Ioga-i-Celo-Pubol.png 1536w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n            <div class=\"item-location\">\n            Castell Gala Dal\u00ed            <\/div>\n\n            \n\n            \n\n        <\/div>\n        <div class=\"item-content\">\n\n                        <a href=\"https:\/\/www.salvador-dali.org\/ca\/educacio-i-activitats\/activitat\/ioga-al-castell-de-pubol\/\"><div class=\"title\">Ioga al Castell de P\u00fabol<\/div><\/a>\n            <div class=\"item-data\">\n            6 de juny, 21 de juny i 4 de juliol de 2026 a les 08:30            <\/div>\n            <div class=\"excerpt\">Submergeix-te en una experi\u00e8ncia de benestar que fusiona cos, art i ess\u00e8ncies en un espai ple de simbolisme<\/div>\n        <\/div>\n\t\t\n\t<\/li>\n\t\n  \t<li class=\"grid-item\">\n\n        \t\t\n        <div class=\"item-header\">\n            <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"232\" height=\"300\" src=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/05\/Salvador-Dali-Divina-Comedia-Rue-Trajan-232x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/05\/Salvador-Dali-Divina-Comedia-Rue-Trajan-232x300.jpg 232w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/05\/Salvador-Dali-Divina-Comedia-Rue-Trajan-791x1024.jpg 791w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/05\/Salvador-Dali-Divina-Comedia-Rue-Trajan-768x994.jpg 768w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/05\/Salvador-Dali-Divina-Comedia-Rue-Trajan-1187x1536.jpg 1187w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/05\/Salvador-Dali-Divina-Comedia-Rue-Trajan-1583x2048.jpg 1583w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/05\/Salvador-Dali-Divina-Comedia-Rue-Trajan-scaled.jpg 1978w\" sizes=\"auto, (max-width: 232px) 100vw, 232px\" \/><\/figure>\n\n            <div class=\"item-location\">\n            Teatre-Museu Dal\u00ed            <\/div>\n\n            \n\n            \n\n        <\/div>\n        <div class=\"item-content\">\n\n                        <a href=\"https:\/\/www.salvador-dali.org\/ca\/educacio-i-activitats\/activitat\/rue-trajan-la-divina-comedia\/\"><div class=\"title\">Rue Trajan: La Divina Com\u00e8dia<\/div><\/a>\n            <div class=\"item-data\">\n            29 de maig i 11 de juny de 2026 a les 19:15            <\/div>\n            <div class=\"excerpt\">Cicle de confer\u00e8ncies dedicat a l'obra gr\u00e0fica de Salvador Dal\u00ed, amb una primera edici\u00f3 dedicada a La Divina Com\u00e8dia<\/div>\n        <\/div>\n\t\t\n\t<\/li>\n\t\n  \t<li class=\"grid-item\">\n\n        \t\t\n        <div class=\"item-header\">\n            <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/04\/Dia-Internacional-Museus-Dali-300x169.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/04\/Dia-Internacional-Museus-Dali-300x169.jpg 300w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/04\/Dia-Internacional-Museus-Dali-1024x576.jpg 1024w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/04\/Dia-Internacional-Museus-Dali-768x432.jpg 768w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/04\/Dia-Internacional-Museus-Dali-1536x864.jpg 1536w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/04\/Dia-Internacional-Museus-Dali.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n            <div class=\"item-location\">\n            Teatre-Museu Dal\u00ed            <\/div>\n\n            \n\n            \n\n        <\/div>\n        <div class=\"item-content\">\n\n                        <a href=\"https:\/\/www.salvador-dali.org\/ca\/educacio-i-activitats\/activitat\/dia-internacional-dels-museus-2026\/\"><div class=\"title\">Dia Internacional dels Museus 2026<\/div><\/a>\n            <div class=\"item-data\">\n            16 de maig de 2026 18:00 a 20:00            <\/div>\n            <div class=\"excerpt\">Vine a veure l'exposici\u00f3 \"Dal\u00ed i les il\u00b7lusions \u00f2ptiques\" i les nostres visites de Visible Thinking!<\/div>\n        <\/div>\n\t\t\n\t<\/li>\n\t\n  \t<li class=\"grid-item\">\n\n        \t\t\n        <div class=\"item-header\">\n            <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"182\" src=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/03\/Taller-familiar-2-300x182.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/03\/Taller-familiar-2-300x182.png 300w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/03\/Taller-familiar-2-1024x623.png 1024w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/03\/Taller-familiar-2-768x467.png 768w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/03\/Taller-familiar-2-1536x934.png 1536w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/03\/Taller-familiar-2.png 1805w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n            <div class=\"item-location\">\n            Teatre-Museu Dal\u00ed            <\/div>\n\n            \n\n            \n\n        <\/div>\n        <div class=\"item-content\">\n\n                        <a href=\"https:\/\/www.salvador-dali.org\/ca\/educacio-i-activitats\/activitat\/en-familia-contacontes-al-museu-dali\/\"><div class=\"title\">En fam\u00edlia: contacontes al Museu Dal\u00ed<\/div><\/a>\n            <div class=\"item-data\">\n            18 d&#039;abril de 2026 a les 16:30            <\/div>\n            <div class=\"excerpt\">Una oportunitat \u00fanica per viure la m\u00e0gia de Sant Jordi en fam\u00edlia, en un entorn cultural incomparable!<\/div>\n        <\/div>\n\t\t\n\t<\/li>\n\t\n  \t<li class=\"grid-item\">\n\n        \t\t\n        <div class=\"item-header\">\n            <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"158\" src=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/02\/religiositat-gavarres-dali-1-300x158.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/02\/religiositat-gavarres-dali-1-300x158.png 300w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/02\/religiositat-gavarres-dali-1-1024x540.png 1024w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/02\/religiositat-gavarres-dali-1-768x405.png 768w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/02\/religiositat-gavarres-dali-1-1536x810.png 1536w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/02\/religiositat-gavarres-dali-1-2048x1081.png 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n            <div class=\"item-location\">\n            Castell Gala Dal\u00ed            <\/div>\n\n            \n\n            \n\n        <\/div>\n        <div class=\"item-content\">\n\n                        <a href=\"https:\/\/www.salvador-dali.org\/ca\/educacio-i-activitats\/activitat\/la-religiositat-a-les-gavarres-el-cami-espiritual-dalinia\/\"><div class=\"title\">La religiositat a les Gavarres: el cam\u00ed espiritual dalini\u00e0<\/div><\/a>\n            <div class=\"item-data\">\n            14 i 15 de mar\u00e7 de 2026            <\/div>\n            <div class=\"excerpt\">Jornades d\u2019espiritualitat i patrimoni a l\u2019Empord\u00e0, centrades en la dimensi\u00f3 religiosa i simb\u00f2lica de l\u2019obra de Salvador Dal\u00ed<\/div>\n        <\/div>\n\t\t\n\t<\/li>\n\t\n  \t<li class=\"grid-item\">\n\n        \t\t\n        <div class=\"item-header\">\n            <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"226\" height=\"300\" src=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/11\/F0482baixa-226x300.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/11\/F0482baixa-226x300.jpg 226w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/11\/F0482baixa-773x1024.jpg 773w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/11\/F0482baixa-768x1018.jpg 768w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/11\/F0482baixa-1159x1536.jpg 1159w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/11\/F0482baixa-1545x2048.jpg 1545w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/11\/F0482baixa.jpg 1923w\" sizes=\"auto, (max-width: 226px) 100vw, 226px\" \/><\/figure>\n\n            <div class=\"item-location\">\n            Casa Salvador Dal\u00ed            <\/div>\n\n            \n\n            \n\n        <\/div>\n        <div class=\"item-content\">\n\n                        <a href=\"https:\/\/www.salvador-dali.org\/ca\/educacio-i-activitats\/activitat\/portlligat-on-lolivera-el-mar-i-el-vent-dansen-amb-la-via-lactea\/\"><div class=\"title\">Portlligat, on l&#8217;olivera, el mar i el vent dansen amb la Via L\u00e0ctea<\/div><\/a>\n            <div class=\"item-data\">\n            29 de novembre de 2025 a les 11:30            <\/div>\n            <div class=\"excerpt\">Cicle d'accions a Portlligat dins les activitats complement\u00e0ries de \u00abLa Madona de Portlligat. Una explosi\u00f3 on\u00edrica\u00bb<\/div>\n        <\/div>\n\t\t\n\t<\/li>\n\t\n  \t<li class=\"grid-item\">\n\n        \t\t\n        <div class=\"item-header\">\n            <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"185\" src=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/11\/taller-infantil-museu-300x185.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Un infant realitzant un collage durant un taller infantil\" srcset=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/11\/taller-infantil-museu-300x185.jpg 300w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/11\/taller-infantil-museu-1024x632.jpg 1024w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/11\/taller-infantil-museu-768x474.jpg 768w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/11\/taller-infantil-museu-1536x948.jpg 1536w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/11\/taller-infantil-museu-2048x1263.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n            <div class=\"item-location\">\n            Teatre-Museu Dal\u00ed            <\/div>\n\n            \n\n            \n\n        <\/div>\n        <div class=\"item-content\">\n\n                        <a href=\"https:\/\/www.salvador-dali.org\/ca\/educacio-i-activitats\/activitat\/taller-familiar-calendari-dels-tresors\/\"><div class=\"title\">Taller familiar: el calendari dels tresors<\/div><\/a>\n            <div class=\"item-data\">\n            30 de novembre de 2025 a les 11:00            <\/div>\n            <div class=\"excerpt\">Amb la Madona de Portlligat, tornen els tallers familiars als Museus Dal\u00ed!<\/div>\n        <\/div>\n\t\t\n\t<\/li>\n\t\n  \t<li class=\"grid-item\">\n\n        \t\t\n        <div class=\"item-header\">\n            <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"235\" height=\"300\" src=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/10\/1-235x300.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Infants realitzant un taller amb pintures i altres materials\" srcset=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/10\/1-235x300.png 235w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/10\/1-802x1024.png 802w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/10\/1-768x981.png 768w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/10\/1-1202x1536.png 1202w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/10\/1-1603x2048.png 1603w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/10\/1.png 1907w\" sizes=\"auto, (max-width: 235px) 100vw, 235px\" \/><\/figure>\n\n            <div class=\"item-location\">\n            Teatre-Museu Dal\u00ed            <\/div>\n\n            \n\n            \n\n        <\/div>\n        <div class=\"item-content\">\n\n                        <a href=\"https:\/\/www.salvador-dali.org\/ca\/educacio-i-activitats\/activitat\/taller-familiar-un-santuari-per-capes\/\"><div class=\"title\">Taller familiar: un santuari per capes<\/div><\/a>\n            <div class=\"item-data\">\n            19 d&#039;octubre i 26 d&#039;octubre de 2025 a les 11:00            <\/div>\n            <div class=\"excerpt\">Amb la Madona de Portlligat, tornen els tallers familiars als Museus Dal\u00ed!<\/div>\n        <\/div>\n\t\t\n\t<\/li>\n\t\n  \t<li class=\"grid-item\">\n\n        \t\t\n        <div class=\"item-header\">\n            <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"148\" src=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/09\/Fons-300x148.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/09\/Fons-300x148.jpg 300w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/09\/Fons-1024x505.jpg 1024w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/09\/Fons-768x379.jpg 768w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/09\/Fons-1536x758.jpg 1536w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/09\/Fons-2048x1010.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n            <div class=\"item-location\">\n            Teatre-Museu Dal\u00ed            <\/div>\n\n            \n\n            \n\n        <\/div>\n        <div class=\"item-content\">\n\n                        <a href=\"https:\/\/www.salvador-dali.org\/ca\/educacio-i-activitats\/activitat\/converses-madona-de-portlligat\/\"><div class=\"title\">Converses entorn de la Madona de Portlligat<\/div><\/a>\n            <div class=\"item-data\">\n            8 d\u2019octubre de 2025 - 27 de novembre de 2025<br>            <\/div>\n            <div class=\"excerpt\">Cicle de confer\u00e8ncies de l'exposici\u00f3 temporal La Madona de Portlligat. Una explosi\u00f3 on\u00edrica<\/div>\n        <\/div>\n\t\t\n\t<\/li>\n\t\n  \t<li class=\"grid-item\">\n\n        \t\t\n        <div class=\"item-header\">\n            <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"234\" src=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/08\/Celebrant-Gala-2025-300x234.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Fotografia del rostre de Gala, amb un reflex de color verd\" srcset=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/08\/Celebrant-Gala-2025-300x234.png 300w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/08\/Celebrant-Gala-2025-1024x799.png 1024w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/08\/Celebrant-Gala-2025-768x599.png 768w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/08\/Celebrant-Gala-2025-1536x1198.png 1536w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/08\/Celebrant-Gala-2025.png 1772w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n            <div class=\"item-location\">\n            Castell Gala Dal\u00ed            <\/div>\n\n            \n\n            \n\n        <\/div>\n        <div class=\"item-content\">\n\n                        <a href=\"https:\/\/www.salvador-dali.org\/ca\/educacio-i-activitats\/activitat\/celebrant-gala-lesperit-lliure\/\"><div class=\"title\">Celebrant Gala: \u00abL&#8217;esperit lliure\u00bb<\/div><\/a>\n            <div class=\"item-data\">\n            26 d&#039;agost de 2025 a les 19:00            <\/div>\n            <div class=\"excerpt\">Espectacle titulat L\u2019esperit lliure: Gala sota la mirada de Paul \u00c9luard, on es combina poesia amb m\u00fasica i una especial posada en escena, al Castell Gala Dal\u00ed.<\/div>\n        <\/div>\n\t\t\n\t<\/li>\n\t\n  \t<li class=\"grid-item\">\n\n        \t\t\n        <div class=\"item-header\">\n            <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/07\/Pubol-55-300x200.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/07\/Pubol-55-300x200.jpg 300w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/07\/Pubol-55-1024x683.jpg 1024w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/07\/Pubol-55-768x512.jpg 768w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/07\/Pubol-55-1536x1024.jpg 1536w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/07\/Pubol-55-2048x1366.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n            <div class=\"item-location\">\n            Castell Gala Dal\u00ed            <\/div>\n\n            \n\n            \n\n        <\/div>\n        <div class=\"item-content\">\n\n                        <a href=\"https:\/\/www.salvador-dali.org\/ca\/educacio-i-activitats\/activitat\/gala-de-vespre\/\"><div class=\"title\">Vespres de Gala<\/div><\/a>\n            <div class=\"item-data\">\n            16 de juliol de 2026 - 21 d\u2019agost de 2026<br>            <\/div>\n            <div class=\"excerpt\">Gaudeix d\u2019una experi\u00e8ncia \u00fanica al Castell Gala Dal\u00ed sota la llum del capvespre, on les estances privades i el jard\u00ed d\u2019escultures esdevenen escenaris d\u2019una visita po\u00e8tica i profundament daliniana.<\/div>\n        <\/div>\n\t\t\n\t<\/li>\n\t\n  \t<li class=\"grid-item\">\n\n        \t\t\n        <div class=\"item-header\">\n            <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"295\" src=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/06\/Films-Surrealistes-Lynch-1-300x295.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/06\/Films-Surrealistes-Lynch-1-300x295.png 300w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/06\/Films-Surrealistes-Lynch-1-1024x1007.png 1024w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/06\/Films-Surrealistes-Lynch-1-768x755.png 768w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/06\/Films-Surrealistes-Lynch-1-1536x1511.png 1536w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/06\/Films-Surrealistes-Lynch-1-2048x2014.png 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n            <div class=\"item-location\">\n            Teatre-Museu Dal\u00ed            <\/div>\n\n            \n\n            \n\n        <\/div>\n        <div class=\"item-content\">\n\n                        <a href=\"https:\/\/www.salvador-dali.org\/ca\/educacio-i-activitats\/activitat\/presentacio-cicle-dali-nocturn-films-surrealistes-2026\/\"><div class=\"title\">Presentaci\u00f3 del Cicle Dal\u00ed Nocturn. Films Surrealistes<\/div><\/a>\n            <div class=\"item-data\">\n            30 de juliol de 2026 - 20 d\u2019agost de 2026<br>            <\/div>\n            <div class=\"excerpt\">Enguany dedicat al cineasta nord-americ\u00e0 David Lynch (1946-2025) amb la confer\u00e8ncia \"David Lynch. M\u00fasiques i sons per a un m\u00f3n estrany\"<\/div>\n        <\/div>\n\t\t\n\t<\/li>\n\t\n  \t<li class=\"grid-item\">\n\n        \t\t\n        <div class=\"item-header\">\n            <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/03\/Conferencia-Tous-Joies-Dali-web-300x169.png\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/03\/Conferencia-Tous-Joies-Dali-web-300x169.png 300w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/03\/Conferencia-Tous-Joies-Dali-web-1024x576.png 1024w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/03\/Conferencia-Tous-Joies-Dali-web-768x432.png 768w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/03\/Conferencia-Tous-Joies-Dali-web.png 1366w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n            <div class=\"item-location\">\n            Teatre-Museu Dal\u00ed            <\/div>\n\n            \n\n            \n\n        <\/div>\n        <div class=\"item-content\">\n\n                        <a href=\"https:\/\/www.salvador-dali.org\/ca\/educacio-i-activitats\/activitat\/les-gemmes-de-les-joies-de-dali\/\"><div class=\"title\">Les gemmes de les Joies de Dal\u00ed<\/div><\/a>\n            <div class=\"item-data\">\n            9 d&#039;abril de 2026 a les 19:15            <\/div>\n            <div class=\"excerpt\">Confer\u00e8ncia a c\u00e0rrec de Rosa Tous, gemm\u00f2loga, sobre la col\u00b7lecci\u00f3 Dal\u00ed-Joies<\/div>\n        <\/div>\n\t\t\n\t<\/li>\n\t\n  \t<li class=\"grid-item\">\n\n        \t\t\n        <div class=\"item-header\">\n            <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"173\" src=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/07\/xerrada-300x173.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Fragment del cartell del cicle de cinema surrealista. Fotomuntatge a partir d&#039;una fotografia de Luis Bu\u00f1uel i d&#039;un fotograma d&#039;Un chien Andalou\" srcset=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/07\/xerrada-300x173.jpg 300w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/07\/xerrada-1024x590.jpg 1024w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/07\/xerrada-768x442.jpg 768w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/07\/xerrada-1536x885.jpg 1536w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/07\/xerrada-2048x1180.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n            <div class=\"item-location\">\n            Teatre-Museu Dal\u00ed            <\/div>\n\n            \n\n            \n\n        <\/div>\n        <div class=\"item-content\">\n\n                        <a href=\"https:\/\/www.salvador-dali.org\/ca\/educacio-i-activitats\/activitat\/presentacio-del-cicle-de-cinema-surrealista\/\"><div class=\"title\">Presentaci\u00f3 del Cicle Dal\u00ed Nocturn. Films Surrealistes<\/div><\/a>\n            <div class=\"item-data\">\n            31 de juliol de 2025 - 21 d\u2019agost de 2025<br>            <\/div>\n            <div class=\"excerpt\">Enguany, el Cicle de Cinema Surrealista tindr\u00e0 una sessi\u00f3 inaugural amb la pres\u00e8ncia de Jordi Xifra, director del Centro Bu\u00f1uel Calanda. Conversar\u00e0 amb el periodista cultural Agus Izquierdo<\/div>\n        <\/div>\n\t\t\n\t<\/li>\n\t\n  \t<li class=\"grid-item\">\n\n        \t\t\n        <div class=\"item-header\">\n            <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"199\" src=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/02\/Visita-guiada-museu-dali-cadillac-300x199.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Grup de persones al voltant del Cadillac del Museu Dal\u00ed\" srcset=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/02\/Visita-guiada-museu-dali-cadillac-300x199.jpg 300w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/02\/Visita-guiada-museu-dali-cadillac-1024x678.jpg 1024w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/02\/Visita-guiada-museu-dali-cadillac-768x509.jpg 768w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/02\/Visita-guiada-museu-dali-cadillac-1536x1017.jpg 1536w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/02\/Visita-guiada-museu-dali-cadillac-2048x1356.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n            <div class=\"item-location\">\n            Teatre-Museu Dal\u00ed            <\/div>\n\n            \n\n            \n\n        <\/div>\n        <div class=\"item-content\">\n\n                        <a href=\"https:\/\/www.salvador-dali.org\/ca\/educacio-i-activitats\/activitat\/visita-guiada-al-teatre-museu-dali\/\"><div class=\"title\">Visita Guiada al Teatre-Museu Dal\u00ed<\/div><\/a>\n            <div class=\"item-data\">\n                        <\/div>\n            <div class=\"excerpt\">El Teatre-Museu de Figueres \u00e9s l&#8217;objecte surrealista m\u00e9s gran del m\u00f3n. Realitzeu una visita guiada per l&#8217;edifici i no us perdeu ni un detall de l&#8217;espai m\u00e9s singular de l&#8217;univers dalini\u00e0. Durada de la visita 60 min. Reserva la Visita Guiada amb les teves entrades al Teatre-Museu Dal\u00ed.<\/div>\n        <\/div>\n\t\t\n\t<\/li>\n\t\n  \t<li class=\"grid-item\">\n\n        \t\t\n        <div class=\"item-header\">\n            <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/06\/IntroVisitaPB-300x225.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/06\/IntroVisitaPB-300x225.jpg 300w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/06\/IntroVisitaPB-1024x768.jpg 1024w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/06\/IntroVisitaPB-768x576.jpg 768w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/06\/IntroVisitaPB-1536x1152.jpg 1536w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/06\/IntroVisitaPB-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n            <div class=\"item-location\">\n            Castell Gala Dal\u00ed            <\/div>\n\n            \n\n            \n\n        <\/div>\n        <div class=\"item-content\">\n\n                        <a href=\"https:\/\/www.salvador-dali.org\/ca\/educacio-i-activitats\/activitat\/introduccio-a-la-visita-del-castell-gala-dali\/\"><div class=\"title\">Introducci\u00f3 a la visita del Castell Gala-Dal\u00ed<\/div><\/a>\n            <div class=\"item-data\">\n                        <\/div>\n            <div class=\"excerpt\">Explora els primers misteris del Castell Gala Dal\u00ed i endinsa\u2019t en la seva hist\u00f2ria, la vida de Gala i l\u2019univers decoratiu de Dal\u00ed. El personal del Castell Gala Dal\u00ed ofereix introduccions a la visita en les quals, des de la planta baixa, es fa un petit recorregut per la hist\u00f2ria de l&#8217;edifici, la vida de [&hellip;]<\/div>\n        <\/div>\n\t\t\n\t<\/li>\n\t\n  \t<li class=\"grid-item\">\n\n        \t\t\n        <div class=\"item-header\">\n            <figure class=\"image\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"199\" src=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2024\/12\/Visita-Guiada-Castell-Gala-Dali-300x199.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2024\/12\/Visita-Guiada-Castell-Gala-Dali-300x199.jpg 300w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2024\/12\/Visita-Guiada-Castell-Gala-Dali.jpg 480w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n            <div class=\"item-location\">\n            Castell Gala Dal\u00ed            <\/div>\n\n            \n\n            \n\n        <\/div>\n        <div class=\"item-content\">\n\n                        <a href=\"https:\/\/tickets.salvador-dali.org\/ca\/989-castell-gala-dali\/5819-entrada-visita-guiada-castell-gala-dali\/info\"><div class=\"title\">Visita Guiada al Castell Gala-Dal\u00ed<\/div><\/a>\n            <div class=\"item-data\">\n                        <\/div>\n            <div class=\"excerpt\">Recorreu els passadissos i estances on Gala va viure i on Dal\u00ed, entre 1982 i 1984, va deixar la seva empremta final. Amb l\u2019ajuda del nostre guia, exploreu els secrets d\u2019aquest castell ple d\u2019imaginaci\u00f3 i deixeu-vos captivar per la m\u00e0gia d\u2019un espai on l\u2019art i la vida es confonen.<\/div>\n        <\/div>\n\t\t\n\t<\/li>\n\t\n  <\/ul>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Lloc Idiomes Idiomes<\/p>\n","protected":false},"author":1,"featured_media":2744,"parent":95,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"categories":[],"tags":[],"class_list":["post-99","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Activitats - Fundaci\u00f3 Gala - Salvador Dal\u00ed<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salvador-dali.org\/ca\/educacio-i-activitats\/activitats\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Activitats - Fundaci\u00f3 Gala - Salvador Dal\u00ed\" \/>\n<meta property=\"og:description\" content=\"Lloc Idiomes Idiomes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salvador-dali.org\/ca\/educacio-i-activitats\/activitats\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3 Gala - Salvador Dal\u00ed\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MuseusDali\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-08T14:55:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/04\/Activitats-2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1707\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MuseuDali\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/ca\\\/educacio-i-activitats\\\/activitats\\\/\",\"url\":\"https:\\\/\\\/www.salvador-dali.org\\\/ca\\\/educacio-i-activitats\\\/activitats\\\/\",\"name\":\"Activitats - Fundaci\u00f3 Gala - Salvador Dal\u00ed\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/ca\\\/educacio-i-activitats\\\/activitats\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/ca\\\/educacio-i-activitats\\\/activitats\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salvador-dali.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Activitats-2-scaled.jpg\",\"datePublished\":\"2024-12-18T16:35:11+00:00\",\"dateModified\":\"2025-05-08T14:55:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/ca\\\/educacio-i-activitats\\\/activitats\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.salvador-dali.org\\\/ca\\\/educacio-i-activitats\\\/activitats\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/ca\\\/educacio-i-activitats\\\/activitats\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.salvador-dali.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Activitats-2-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.salvador-dali.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Activitats-2-scaled.jpg\",\"width\":1707,\"height\":2560,\"caption\":\"Visitants al Museu Dal\u00ed de Figueres. Pere Duran\\\/Nord Media\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/ca\\\/educacio-i-activitats\\\/activitats\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.salvador-dali.org\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Educaci\u00f3 i Activitats\",\"item\":\"https:\\\/\\\/www.salvador-dali.org\\\/ca\\\/educacio-i-activitats\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Activitats\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.salvador-dali.org\\\/ca\\\/\",\"name\":\"Fundaci\u00f3 Gala - Salvador Dal\u00ed\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salvador-dali.org\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/ca\\\/#organization\",\"name\":\"Fundaci\u00f3 Gala - Salvador Dal\u00ed\",\"url\":\"https:\\\/\\\/www.salvador-dali.org\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.salvador-dali.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/fundacio-gala-salvador-dali.png\",\"contentUrl\":\"https:\\\/\\\/www.salvador-dali.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/fundacio-gala-salvador-dali.png\",\"width\":240,\"height\":240,\"caption\":\"Fundaci\u00f3 Gala - Salvador Dal\u00ed\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MuseusDali\",\"https:\\\/\\\/x.com\\\/MuseuDali\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/FundacioDali\",\"https:\\\/\\\/www.flickr.com\\\/fundacio_dali\\\/\",\"https:\\\/\\\/instagram.com\\\/museudali\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Activitats - Fundaci\u00f3 Gala - Salvador Dal\u00ed","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salvador-dali.org\/ca\/educacio-i-activitats\/activitats\/","og_locale":"ca_ES","og_type":"article","og_title":"Activitats - Fundaci\u00f3 Gala - Salvador Dal\u00ed","og_description":"Lloc Idiomes Idiomes","og_url":"https:\/\/www.salvador-dali.org\/ca\/educacio-i-activitats\/activitats\/","og_site_name":"Fundaci\u00f3 Gala - Salvador Dal\u00ed","article_publisher":"https:\/\/www.facebook.com\/MuseusDali","article_modified_time":"2025-05-08T14:55:17+00:00","og_image":[{"width":1707,"height":2560,"url":"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/04\/Activitats-2-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MuseuDali","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.salvador-dali.org\/ca\/educacio-i-activitats\/activitats\/","url":"https:\/\/www.salvador-dali.org\/ca\/educacio-i-activitats\/activitats\/","name":"Activitats - Fundaci\u00f3 Gala - Salvador Dal\u00ed","isPartOf":{"@id":"https:\/\/www.salvador-dali.org\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salvador-dali.org\/ca\/educacio-i-activitats\/activitats\/#primaryimage"},"image":{"@id":"https:\/\/www.salvador-dali.org\/ca\/educacio-i-activitats\/activitats\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/04\/Activitats-2-scaled.jpg","datePublished":"2024-12-18T16:35:11+00:00","dateModified":"2025-05-08T14:55:17+00:00","breadcrumb":{"@id":"https:\/\/www.salvador-dali.org\/ca\/educacio-i-activitats\/activitats\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salvador-dali.org\/ca\/educacio-i-activitats\/activitats\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.salvador-dali.org\/ca\/educacio-i-activitats\/activitats\/#primaryimage","url":"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/04\/Activitats-2-scaled.jpg","contentUrl":"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/04\/Activitats-2-scaled.jpg","width":1707,"height":2560,"caption":"Visitants al Museu Dal\u00ed de Figueres. Pere Duran\/Nord Media"},{"@type":"BreadcrumbList","@id":"https:\/\/www.salvador-dali.org\/ca\/educacio-i-activitats\/activitats\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.salvador-dali.org\/ca\/"},{"@type":"ListItem","position":2,"name":"Educaci\u00f3 i Activitats","item":"https:\/\/www.salvador-dali.org\/ca\/educacio-i-activitats\/"},{"@type":"ListItem","position":3,"name":"Activitats"}]},{"@type":"WebSite","@id":"https:\/\/www.salvador-dali.org\/ca\/#website","url":"https:\/\/www.salvador-dali.org\/ca\/","name":"Fundaci\u00f3 Gala - Salvador Dal\u00ed","description":"","publisher":{"@id":"https:\/\/www.salvador-dali.org\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salvador-dali.org\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.salvador-dali.org\/ca\/#organization","name":"Fundaci\u00f3 Gala - Salvador Dal\u00ed","url":"https:\/\/www.salvador-dali.org\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.salvador-dali.org\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/04\/fundacio-gala-salvador-dali.png","contentUrl":"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/04\/fundacio-gala-salvador-dali.png","width":240,"height":240,"caption":"Fundaci\u00f3 Gala - Salvador Dal\u00ed"},"image":{"@id":"https:\/\/www.salvador-dali.org\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MuseusDali","https:\/\/x.com\/MuseuDali","https:\/\/www.youtube.com\/user\/FundacioDali","https:\/\/www.flickr.com\/fundacio_dali\/","https:\/\/instagram.com\/museudali"]}]}},"_links":{"self":[{"href":"https:\/\/www.salvador-dali.org\/ca\/wp-json\/wp\/v2\/pages\/99","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salvador-dali.org\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.salvador-dali.org\/ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.salvador-dali.org\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salvador-dali.org\/ca\/wp-json\/wp\/v2\/comments?post=99"}],"version-history":[{"count":1,"href":"https:\/\/www.salvador-dali.org\/ca\/wp-json\/wp\/v2\/pages\/99\/revisions"}],"predecessor-version":[{"id":15502,"href":"https:\/\/www.salvador-dali.org\/ca\/wp-json\/wp\/v2\/pages\/99\/revisions\/15502"}],"up":[{"embeddable":true,"href":"https:\/\/www.salvador-dali.org\/ca\/wp-json\/wp\/v2\/pages\/95"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salvador-dali.org\/ca\/wp-json\/wp\/v2\/media\/2744"}],"wp:attachment":[{"href":"https:\/\/www.salvador-dali.org\/ca\/wp-json\/wp\/v2\/media?parent=99"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.salvador-dali.org\/ca\/wp-json\/wp\/v2\/categories?post=99"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.salvador-dali.org\/ca\/wp-json\/wp\/v2\/tags?post=99"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}