{"id":15947,"date":"2026-05-21T13:51:01","date_gmt":"2026-05-21T11:51:01","guid":{"rendered":"https:\/\/www.salvador-dali.org\/?post_type=activitat&#038;p=15947"},"modified":"2026-05-26T15:21:35","modified_gmt":"2026-05-26T13:21:35","slug":"carta-oberta-salvador-dali","status":"publish","type":"activitat","link":"https:\/\/www.salvador-dali.org\/es\/educacion-y-actividades\/actividad\/carta-oberta-salvador-dali\/","title":{"rendered":"Presentacion del libro \u00abCarta oberta a Salvador Dal\u00ed\u00bb en P\u00fabol"},"content":{"rendered":"\n<div class=\"wp-block-columns col-text col-2 is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\" style=\"font-size:27px\">La traducci\u00f3 catalana ha anat a c\u00e0rrec de Val\u00e8ria Gaillard, publicada per Edicions del Cr\u00e0ter<\/h2>\n\n\n\n    <div class=\"button tickets\"><a target='_blank' href=\"https:\/\/tickets.salvador-dali.org\/ca\/989-castell-gala-dali\/13518-carta-oberta-a-salvador-dali\">Entrades<\/a><\/div>\n\n\n\n    \n\n\n\n\n\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"755\" height=\"1200\" src=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/05\/cartaobertaasalvadordali.jpg\" alt=\"\" class=\"wp-image-15961\" srcset=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/05\/cartaobertaasalvadordali.jpg 755w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/05\/cartaobertaasalvadordali-189x300.jpg 189w, https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/05\/cartaobertaasalvadordali-644x1024.jpg 644w\" sizes=\"auto, (max-width: 755px) 100vw, 755px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Salvador Dal\u00ed presenta a <em>Carta oberta a Salvador Dal\u00ed<\/em> una obra plena d\u2019ironia, provocaci\u00f3 i reflexions sobre l\u2019art, la societat i la seva pr\u00f2pia figura p\u00fablica. Al llarg d\u2019aquest particular intercanvi epistolar apareixen les diferents cares de Dal\u00ed, especialment el Dal\u00ed \u00abgeni\u00bb i el Dal\u00ed \u00abavidadollars\u00bb, l\u2019anagrama creat per Andr\u00e9 Breton per criticar la seva fascinaci\u00f3 pels diners i la fama. L\u2019autor juga constantment amb aquestes etiquetes i se\u2019n riu dels qui intenten definir-lo d\u2019una sola manera. Amb el seu estil extravagant i surrealista, recorda episodis hilarants de la seva arribada a Nova York i recupera algunes de les seves idees m\u00e9s conegudes, com la centralitat mundial de l\u2019estaci\u00f3 de Perpiny\u00e0 o la seva defensa de la monarquia. A m\u00e9s, aprofita l\u2019obra per llan\u00e7ar cr\u00edtiques a figures com Le Corbusier i, alhora, mostrar admiraci\u00f3 per grans mestres de la pintura. Tot plegat es combina amb un llenguatge simb\u00f2lic, teatral i grandiloq\u00fcent que reflecteix perfectament la personalitat exc\u00e8ntrica i \u00fanica de Dal\u00ed, convertint el llibre en una finestra privilegiada al seu univers art\u00edstic i personal.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div class=\"wp-block-coblocks-events wp-block-coblocks-events-front-container\"><div class=\"wp-block-coblocks-front-events-swiper-container\"><div class=\"swiper-wrapper-loading\">\n<div class=\"wp-block-coblocks-event-item swiper-slide\" data-page=\"undefined\"><div class=\"wp-block-coblocks-events__date\"><span class=\"wp-block-coblocks-events__day\">12<\/span><div><span class=\"wp-block-coblocks-events__month\">Juny<\/span><span class=\"wp-block-coblocks-events__year\">2026<\/span><\/div><\/div><div class=\"wp-block-coblocks-events__content\"><span class=\"wp-block-coblocks-events__title\">Presentaci\u00f3 del llibre <em>Carta oberta a Salvador Dal\u00ed<\/em> <\/span><span class=\"wp-block-coblocks-events__description\" itemprop=\"description\">Entrada lliure amb reserva pr\u00e8via<\/span><\/div><div class=\"wp-block-coblocks-events__details\"><span class=\"wp-block-coblocks-events__time\">A les 19:15<\/span><span class=\"wp-block-coblocks-events__location\">Castell Gala Dal\u00ed<\/span><\/div><\/div>\n<\/div><\/div><button class=\"wp-coblocks-events-nav-button__prev\" id=\"wp-coblocks-event-swiper-prev\" style=\"visibility:hidden\"><\/button><button class=\"wp-coblocks-events-nav-button__next\" id=\"wp-coblocks-event-swiper-next\" style=\"visibility:hidden\"><\/button><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n<\/div>\n<\/div>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una obra llena de iron\u00eda, provocaci\u00f3n y reflexiones sobre el arte, la sociedad y su propia figura p\u00fablica<\/p>\n","protected":false},"featured_media":15964,"template":"","meta":{"_acf_changed":true,"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":""},"categoria-activitat":[96],"idioma":[191],"nivell-educatiu":[],"class_list":["post-15947","activitat","type-activitat","status-publish","has-post-thumbnail","hentry","categoria-activitat-actividad","idioma-catalan-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Presentacion del libro &quot;Carta oberta a Salvador Dal\u00ed&quot; en P\u00fabol - Fundaci\u00f3 Gala - Salvador Dal\u00ed<\/title>\n<meta name=\"description\" content=\"Una obra llena de iron\u00eda, provocaci\u00f3n y reflexiones sobre el arte, la sociedad y su propia figura p\u00fablica. La traducci\u00f3n al catal\u00e1n ha estado a cargo de Val\u00e8ria Gaillard, publicada por Edicions del Cr\u00e0ter.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salvador-dali.org\/es\/educacion-y-actividades\/actividad\/carta-oberta-salvador-dali\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presentacion del libro &quot;Carta oberta a Salvador Dal\u00ed&quot; en P\u00fabol - Fundaci\u00f3 Gala - Salvador Dal\u00ed\" \/>\n<meta property=\"og:description\" content=\"Una obra llena de iron\u00eda, provocaci\u00f3n y reflexiones sobre el arte, la sociedad y su propia figura p\u00fablica. La traducci\u00f3n al catal\u00e1n ha estado a cargo de Val\u00e8ria Gaillard, publicada por Edicions del Cr\u00e0ter.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salvador-dali.org\/es\/educacion-y-actividades\/actividad\/carta-oberta-salvador-dali\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3 Gala - Salvador Dal\u00ed\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MuseusDali\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-26T13:21:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/05\/cartaobertaasalvadordali.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"755\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MuseuDali\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/es\\\/educacion-y-actividades\\\/actividad\\\/carta-oberta-salvador-dali\\\/\",\"url\":\"https:\\\/\\\/www.salvador-dali.org\\\/es\\\/educacion-y-actividades\\\/actividad\\\/carta-oberta-salvador-dali\\\/\",\"name\":\"Presentacion del libro \\\"Carta oberta a Salvador Dal\u00ed\\\" en P\u00fabol - Fundaci\u00f3 Gala - Salvador Dal\u00ed\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/es\\\/educacion-y-actividades\\\/actividad\\\/carta-oberta-salvador-dali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/es\\\/educacion-y-actividades\\\/actividad\\\/carta-oberta-salvador-dali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salvador-dali.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/cartaobertaasalvadordali.jpg\",\"datePublished\":\"2026-05-21T11:51:01+00:00\",\"dateModified\":\"2026-05-26T13:21:35+00:00\",\"description\":\"Una obra llena de iron\u00eda, provocaci\u00f3n y reflexiones sobre el arte, la sociedad y su propia figura p\u00fablica. La traducci\u00f3n al catal\u00e1n ha estado a cargo de Val\u00e8ria Gaillard, publicada por Edicions del Cr\u00e0ter.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/es\\\/educacion-y-actividades\\\/actividad\\\/carta-oberta-salvador-dali\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.salvador-dali.org\\\/es\\\/educacion-y-actividades\\\/actividad\\\/carta-oberta-salvador-dali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/es\\\/educacion-y-actividades\\\/actividad\\\/carta-oberta-salvador-dali\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.salvador-dali.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/cartaobertaasalvadordali.jpg\",\"contentUrl\":\"https:\\\/\\\/www.salvador-dali.org\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/cartaobertaasalvadordali.jpg\",\"width\":755,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/es\\\/educacion-y-actividades\\\/actividad\\\/carta-oberta-salvador-dali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.salvador-dali.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presentacion del libro \u00abCarta oberta a Salvador Dal\u00ed\u00bb en P\u00fabol\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.salvador-dali.org\\\/es\\\/\",\"name\":\"Fundaci\u00f3 Gala - Salvador Dal\u00ed\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salvador-dali.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Gala - Salvador Dal\u00ed\",\"url\":\"https:\\\/\\\/www.salvador-dali.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.salvador-dali.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/fundacio-gala-salvador-dali.png\",\"contentUrl\":\"https:\\\/\\\/www.salvador-dali.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/fundacio-gala-salvador-dali.png\",\"width\":240,\"height\":240,\"caption\":\"Fundaci\u00f3 Gala - Salvador Dal\u00ed\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MuseusDali\",\"https:\\\/\\\/x.com\\\/MuseuDali\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/FundacioDali\",\"https:\\\/\\\/www.flickr.com\\\/fundacio_dali\\\/\",\"https:\\\/\\\/instagram.com\\\/museudali\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presentacion del libro \"Carta oberta a Salvador Dal\u00ed\" en P\u00fabol - Fundaci\u00f3 Gala - Salvador Dal\u00ed","description":"Una obra llena de iron\u00eda, provocaci\u00f3n y reflexiones sobre el arte, la sociedad y su propia figura p\u00fablica. La traducci\u00f3n al catal\u00e1n ha estado a cargo de Val\u00e8ria Gaillard, publicada por Edicions del Cr\u00e0ter.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salvador-dali.org\/es\/educacion-y-actividades\/actividad\/carta-oberta-salvador-dali\/","og_locale":"es_ES","og_type":"article","og_title":"Presentacion del libro \"Carta oberta a Salvador Dal\u00ed\" en P\u00fabol - Fundaci\u00f3 Gala - Salvador Dal\u00ed","og_description":"Una obra llena de iron\u00eda, provocaci\u00f3n y reflexiones sobre el arte, la sociedad y su propia figura p\u00fablica. La traducci\u00f3n al catal\u00e1n ha estado a cargo de Val\u00e8ria Gaillard, publicada por Edicions del Cr\u00e0ter.","og_url":"https:\/\/www.salvador-dali.org\/es\/educacion-y-actividades\/actividad\/carta-oberta-salvador-dali\/","og_site_name":"Fundaci\u00f3 Gala - Salvador Dal\u00ed","article_publisher":"https:\/\/www.facebook.com\/MuseusDali","article_modified_time":"2026-05-26T13:21:35+00:00","og_image":[{"width":755,"height":1200,"url":"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/05\/cartaobertaasalvadordali.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MuseuDali","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.salvador-dali.org\/es\/educacion-y-actividades\/actividad\/carta-oberta-salvador-dali\/","url":"https:\/\/www.salvador-dali.org\/es\/educacion-y-actividades\/actividad\/carta-oberta-salvador-dali\/","name":"Presentacion del libro \"Carta oberta a Salvador Dal\u00ed\" en P\u00fabol - Fundaci\u00f3 Gala - Salvador Dal\u00ed","isPartOf":{"@id":"https:\/\/www.salvador-dali.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salvador-dali.org\/es\/educacion-y-actividades\/actividad\/carta-oberta-salvador-dali\/#primaryimage"},"image":{"@id":"https:\/\/www.salvador-dali.org\/es\/educacion-y-actividades\/actividad\/carta-oberta-salvador-dali\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/05\/cartaobertaasalvadordali.jpg","datePublished":"2026-05-21T11:51:01+00:00","dateModified":"2026-05-26T13:21:35+00:00","description":"Una obra llena de iron\u00eda, provocaci\u00f3n y reflexiones sobre el arte, la sociedad y su propia figura p\u00fablica. La traducci\u00f3n al catal\u00e1n ha estado a cargo de Val\u00e8ria Gaillard, publicada por Edicions del Cr\u00e0ter.","breadcrumb":{"@id":"https:\/\/www.salvador-dali.org\/es\/educacion-y-actividades\/actividad\/carta-oberta-salvador-dali\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salvador-dali.org\/es\/educacion-y-actividades\/actividad\/carta-oberta-salvador-dali\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.salvador-dali.org\/es\/educacion-y-actividades\/actividad\/carta-oberta-salvador-dali\/#primaryimage","url":"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/05\/cartaobertaasalvadordali.jpg","contentUrl":"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2026\/05\/cartaobertaasalvadordali.jpg","width":755,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.salvador-dali.org\/es\/educacion-y-actividades\/actividad\/carta-oberta-salvador-dali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.salvador-dali.org\/es\/"},{"@type":"ListItem","position":2,"name":"Presentacion del libro \u00abCarta oberta a Salvador Dal\u00ed\u00bb en P\u00fabol"}]},{"@type":"WebSite","@id":"https:\/\/www.salvador-dali.org\/es\/#website","url":"https:\/\/www.salvador-dali.org\/es\/","name":"Fundaci\u00f3 Gala - Salvador Dal\u00ed","description":"","publisher":{"@id":"https:\/\/www.salvador-dali.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salvador-dali.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.salvador-dali.org\/es\/#organization","name":"Fundaci\u00f3 Gala - Salvador Dal\u00ed","url":"https:\/\/www.salvador-dali.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.salvador-dali.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/04\/fundacio-gala-salvador-dali.png","contentUrl":"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/04\/fundacio-gala-salvador-dali.png","width":240,"height":240,"caption":"Fundaci\u00f3 Gala - Salvador Dal\u00ed"},"image":{"@id":"https:\/\/www.salvador-dali.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MuseusDali","https:\/\/x.com\/MuseuDali","https:\/\/www.youtube.com\/user\/FundacioDali","https:\/\/www.flickr.com\/fundacio_dali\/","https:\/\/instagram.com\/museudali"]}]}},"_links":{"self":[{"href":"https:\/\/www.salvador-dali.org\/es\/wp-json\/wp\/v2\/activitat\/15947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salvador-dali.org\/es\/wp-json\/wp\/v2\/activitat"}],"about":[{"href":"https:\/\/www.salvador-dali.org\/es\/wp-json\/wp\/v2\/types\/activitat"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salvador-dali.org\/es\/wp-json\/wp\/v2\/media\/15964"}],"wp:attachment":[{"href":"https:\/\/www.salvador-dali.org\/es\/wp-json\/wp\/v2\/media?parent=15947"}],"wp:term":[{"taxonomy":"categoria-activitat","embeddable":true,"href":"https:\/\/www.salvador-dali.org\/es\/wp-json\/wp\/v2\/categoria-activitat?post=15947"},{"taxonomy":"idioma","embeddable":true,"href":"https:\/\/www.salvador-dali.org\/es\/wp-json\/wp\/v2\/idioma?post=15947"},{"taxonomy":"nivell-educatiu","embeddable":true,"href":"https:\/\/www.salvador-dali.org\/es\/wp-json\/wp\/v2\/nivell-educatiu?post=15947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}