{"id":8804,"date":"2017-11-13T00:00:00","date_gmt":"2017-11-12T22:00:00","guid":{"rendered":"https:\/\/www.salvador-dali.org\/fundacio-dali\/noticia\/s-exposa-figura-de-perfil\/"},"modified":"2025-06-26T10:11:24","modified_gmt":"2025-06-26T08:11:24","slug":"se-expone-figura-de-perfil","status":"publish","type":"noticia","link":"https:\/\/www.salvador-dali.org\/es\/fundacion-dali\/noticia\/se-expone-figura-de-perfil\/","title":{"rendered":"Se expone Figura de perfil"},"content":{"rendered":"<p>Se ha inaugurado una exposici\u00f3n temporal en el Teatro-Museo Dal\u00ed de Figueres. Montse Aguer, directora de los Museos Dal\u00ed y comisaria de la muestra la ha descrito como una forma de evocar la exposici\u00f3n monogr\u00e1fica en las Galeries Dalmau del a\u00f1o 1925, donde se expuso <em>Figura de perfil <\/em>por primera y \u00fanica vez, un retrato de Anna Maria, su hermana, que fue adquirido por la Fundaci\u00f3n Dal\u00ed el marzo pasado en la casa de subastas Bonham&#8217;s de Londres.<\/p>\n<p>La muestra se titula <strong><em>Salvador Dal\u00ed, aprendiz de pintor<\/em><\/strong> y podr\u00e1 verse desde ma\u00f1ana, 14 de noviembre, hasta finales de 2018 en una de las Salas de las Loggias, en el Teatro-Museo Dal\u00ed de Figueres. Se ha hecho coincidir el primer d\u00eda de visita con la fecha en la que se inaugur\u00f3 la exposici\u00f3n en las Galeries Dalmau de 1925.<\/p>\n<p><strong>Concepto y contenido<\/strong><\/p>\n<p>El 14 de noviembre de 1925, cuando, con solo veinti\u00fan a\u00f1os, expone de manera individual unas obras -17 pinturas y 5 dibujos- entre las cuales hay la m\u00e1s desconocida de todas, Figura de perfil. La prensa de la \u00e9poca comenta ampliamente la exposici\u00f3n de este aprendiz de pintor y coincide en destacar la presencia simult\u00e1nea en Salvador Dal\u00ed de planteamientos vanguardistas con una destacable incidencia cubista y un estilo que remite a la tradici\u00f3n, concretamente a Ingres. De hecho, tres citas que el pintor incluye en el cat\u00e1logo est\u00e1n extra\u00eddas de este volumen en el que Ingres reflexiona sobre la pintura, expresando algunos de los conceptos que Dal\u00ed ten\u00eda en aquellos momentos sobre esta disciplina art\u00edstica.<\/p>\n<p>El propio Dal\u00ed se refiere posteriormente a este per\u00edodo inicial de experimentaci\u00f3n constante que se hace evidente en la muestra de las Dalmau: \u00abYo pintaba los paisajes de Cadaqu\u00e9s; mi padre, mi hermana, todo estaba sujeto a mi frenes\u00ed. Me interesaba por la pintura de Chirico, que conoc\u00eda por las revistas. Colaboraba en la Gaseta de les Arts de Barcelona y en L&#8217;Amic de les Arts; y ten\u00eda un libro que no abandonaba mi cabecera: los Pensamientos de Ingres. Decid\u00ed extraer unas frases significativas para el texto del cat\u00e1logo de mi primera exposici\u00f3n individual\u00bb.<\/p>\n<p>En esta primera exposici\u00f3n individual, Dal\u00ed present\u00f3 17 \u00f3leos y 5 dibujos. Seis de las pinturas expuestas son retratos de su hermana Anna Maria, pr\u00e1cticamente siempre de espaldas al espectador. Tambi\u00e9n presenta otros retratos -como el Retrato de mi padre, el Retrato de Ramoneta Montsalvatge y el Retrato de Maria Carbona, dos amistades femeninas de la familia Dal\u00ed-, acompa\u00f1ados de otras obras que tienen el paisaje como tema central.<\/p>\n<p><em><strong>Figura de perfil<\/strong><\/em><\/p>\n<p><em>Figura de perfil<\/em> es adquirida por 500 pesetas por el farmac\u00e9utico y amigo de la familia Joaquim Cus\u00ed i Furtunet, y no vuelve a ser exhibida hasta que la casa Bonham&#8217;s de Londres la subasta el 2 de marzo de 2017, cuando la compra la Fundaci\u00f3n Dal\u00ed. Hasta ahora, solo se ten\u00eda constancia de la obra a partir de una reproducci\u00f3n en blanco y negro publicada en la revista Atl\u00e1ntico en 1929.<\/p>\n<p>La figura central de la obra es Anna Maria, su principal modelo hasta la aparici\u00f3n de Gala en 1929. Anna Maria refleja por escrito los momentos de compenetraci\u00f3n plena con su hermano: \u00abLos retratos m\u00edos que mi hermano pint\u00f3 en esta \u00e9poca son incontables. Muchos de ellos eran meros estudios de bucles y de un hombro siempre descubierto. Pintaba paciente e infatigablemente, y a m\u00ed no me cansaba posar para \u00e9l, pues nunca me ha aburrido el permanecer quieta y silenciosa\u00bb. Y contin\u00faa: \u00abDurante las horas en que le serv\u00eda de modelo, yo no me cansaba de observar aquel paisaje que ya, para siempre, ha formado parte de mi vida. Pues siempre me pintaba cerca de alguna ventana\u00bb.<\/p>\n<p>La simplicidad de las l\u00edneas y el tratamiento de los espacios vac\u00edos de la estancia crean una atm\u00f3sfera tranquila. La posici\u00f3n de tres cuartos de perfil de la joven y la direccionalidad de su mirada generan un movimiento suave y dirigen toda la atenci\u00f3n del espectador hacia el cuadrante superior izquierdo de la pieza, donde el paisaje de Cadaqu\u00e9s es visible desde la ventana. Un paisaje claramente identificado como Es Sortell, un paraje situado cerca de la casa de los Pichot, familia de artistas pr\u00f3xima a los Dal\u00ed, con el caracter\u00edstico puente que comunica con la isla adyacente y que Dal\u00ed pod\u00eda contemplar desde la ventana de su estudio en la casa paterna de Es Llaner.<\/p>\n<p>La suavidad de los colores se intensifica en la zona destacada a base de pinceladas cubrientes que marcan la textura del paisaje mediante azules cielo, blancos y ocres; en el marco de la ventana con colores crudos, blancos y verdes azulados; y en la figura y el vestido con tonalidades carne y rosadas. En contraste, en las zonas que permanecen en la penumbra de la habitaci\u00f3n predominan los colores oscuros, grises y marrones aplicados con una capa pict\u00f3rica fina y diluida, casi transparente en la zona de las nalgas. Figura de perfil evidencia un distanciamiento de la entusiasta paleta colorista del impresionismo para acercarse a las posiciones del cubismo y de la revista Valori Plastici, todo ello enmarcado en un paisaje de lo esencial, de lo eterno, que se har\u00e1 ic\u00f3nico: el de Cadaqu\u00e9s. Un retrato que predice a Salvador Dal\u00ed, como tambi\u00e9n lo predicen los otros cuatro \u00f3leos, todos ellos propiedad de la Fundaci\u00f3n Dal\u00ed, que lo acompa\u00f1an y lo complementan y que ejemplifican, con perfecta claridad en esta muestra, la \u00e9poca de aprendizaje de Salvador Dal\u00ed.<\/p>\n<p><strong>Montaje<\/strong><\/p>\n<p>El montaje de la exposici\u00f3n ha sido dise\u00f1ado por Pep Canaleta de 3carme33 y el grafismo, por Alex Gifreu. Evoca la decoraci\u00f3n de las Galeries Dalmau de aquel 1925, a\u00f1o en que se celebr\u00f3 la primera monogr\u00e1fica dedicada al joven Dal\u00ed. Se han forrado las paredes con una tela de seda color rosa, se ha colocado un z\u00f3calo ancho de madera y se ha complementado con una mesa donde se proyectan las otras obras que integraban la exposici\u00f3n monogr\u00e1fica de las Galeries Dalmau y que no pertenecen a los fondos de la Fundaci\u00f3n Dal\u00ed.<\/p>\n<p>El Servicio Educativo ha editado un librito con textos de Montse Aguer, con la colaboraci\u00f3n de Irene Civil, jefa de Conservaci\u00f3n y Restauraci\u00f3n, y la coordinaci\u00f3n de Cuca R. Costa, del Centro de Estudios Dalinianos. As\u00ed mismo se ha preparado una campa\u00f1a para las redes sociales que consta de tres documentos audiovisuales, c\u00e1psulas, realizados por DocDoc Films, que, una vez inaugurada la exposici\u00f3n se podr\u00e1n ver como un documento unitario en la web, en la secci\u00f3n dedicada a la muestra que pod\u00e9is ver <a href=\"https:\/\/exhibitions.salvador-dali.org\/es\/salvador-dali-aprendiz-pintor\/\">aqu\u00ed<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se ha inaugurado una exposici\u00f3n temporal en el Teatro-Museo Dal\u00ed de Figueres. Montse Aguer, directora de los Museos Dal\u00ed y comisaria de la muestra la ha descrito como una forma de evocar la exposici\u00f3n monogr\u00e1fica en las Galeries Dalmau del a\u00f1o 1925, donde se expuso Figura de perfil por primera y \u00fanica vez, un retrato [&hellip;]<\/p>\n","protected":false},"featured_media":5396,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false,"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":""},"categoria-actualitat":[117,118,119],"class_list":["post-8804","noticia","type-noticia","status-publish","format-standard","has-post-thumbnail","hentry","categoria-actualitat-exposiciones","categoria-actualitat-fundacion-gala-salvador-dali","categoria-actualitat-museos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Se expone Figura de perfil - Fundaci\u00f3 Gala - Salvador Dal\u00ed<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salvador-dali.org\/es\/fundacion-dali\/noticia\/se-expone-figura-de-perfil\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se expone Figura de perfil - Fundaci\u00f3 Gala - Salvador Dal\u00ed\" \/>\n<meta property=\"og:description\" content=\"Se ha inaugurado una exposici\u00f3n temporal en el Teatro-Museo Dal\u00ed de Figueres. Montse Aguer, directora de los Museos Dal\u00ed y comisaria de la muestra la ha descrito como una forma de evocar la exposici\u00f3n monogr\u00e1fica en las Galeries Dalmau del a\u00f1o 1925, donde se expuso Figura de perfil por primera y \u00fanica vez, un retrato [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salvador-dali.org\/es\/fundacion-dali\/noticia\/se-expone-figura-de-perfil\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3 Gala - Salvador Dal\u00ed\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MuseusDali\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-26T08:11:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/05\/muntatgesala2_151066949677_1024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MuseuDali\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/es\\\/fundacion-dali\\\/noticia\\\/se-expone-figura-de-perfil\\\/\",\"url\":\"https:\\\/\\\/www.salvador-dali.org\\\/es\\\/fundacion-dali\\\/noticia\\\/se-expone-figura-de-perfil\\\/\",\"name\":\"Se expone Figura de perfil - Fundaci\u00f3 Gala - Salvador Dal\u00ed\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/es\\\/fundacion-dali\\\/noticia\\\/se-expone-figura-de-perfil\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/es\\\/fundacion-dali\\\/noticia\\\/se-expone-figura-de-perfil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salvador-dali.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/muntatgesala2_151066949677_1024.jpg\",\"datePublished\":\"2017-11-12T22:00:00+00:00\",\"dateModified\":\"2025-06-26T08:11:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/es\\\/fundacion-dali\\\/noticia\\\/se-expone-figura-de-perfil\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.salvador-dali.org\\\/es\\\/fundacion-dali\\\/noticia\\\/se-expone-figura-de-perfil\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/es\\\/fundacion-dali\\\/noticia\\\/se-expone-figura-de-perfil\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.salvador-dali.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/muntatgesala2_151066949677_1024.jpg\",\"contentUrl\":\"https:\\\/\\\/www.salvador-dali.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/muntatgesala2_151066949677_1024.jpg\",\"width\":1024,\"height\":1536,\"caption\":\"Figura de perfil\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/es\\\/fundacion-dali\\\/noticia\\\/se-expone-figura-de-perfil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.salvador-dali.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se expone Figura de perfil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.salvador-dali.org\\\/es\\\/\",\"name\":\"Fundaci\u00f3 Gala - Salvador Dal\u00ed\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salvador-dali.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Gala - Salvador Dal\u00ed\",\"url\":\"https:\\\/\\\/www.salvador-dali.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.salvador-dali.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/fundacio-gala-salvador-dali.png\",\"contentUrl\":\"https:\\\/\\\/www.salvador-dali.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/fundacio-gala-salvador-dali.png\",\"width\":240,\"height\":240,\"caption\":\"Fundaci\u00f3 Gala - Salvador Dal\u00ed\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MuseusDali\",\"https:\\\/\\\/x.com\\\/MuseuDali\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/FundacioDali\",\"https:\\\/\\\/www.flickr.com\\\/fundacio_dali\\\/\",\"https:\\\/\\\/instagram.com\\\/museudali\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se expone Figura de perfil - Fundaci\u00f3 Gala - Salvador Dal\u00ed","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salvador-dali.org\/es\/fundacion-dali\/noticia\/se-expone-figura-de-perfil\/","og_locale":"es_ES","og_type":"article","og_title":"Se expone Figura de perfil - Fundaci\u00f3 Gala - Salvador Dal\u00ed","og_description":"Se ha inaugurado una exposici\u00f3n temporal en el Teatro-Museo Dal\u00ed de Figueres. Montse Aguer, directora de los Museos Dal\u00ed y comisaria de la muestra la ha descrito como una forma de evocar la exposici\u00f3n monogr\u00e1fica en las Galeries Dalmau del a\u00f1o 1925, donde se expuso Figura de perfil por primera y \u00fanica vez, un retrato [&hellip;]","og_url":"https:\/\/www.salvador-dali.org\/es\/fundacion-dali\/noticia\/se-expone-figura-de-perfil\/","og_site_name":"Fundaci\u00f3 Gala - Salvador Dal\u00ed","article_publisher":"https:\/\/www.facebook.com\/MuseusDali","article_modified_time":"2025-06-26T08:11:24+00:00","og_image":[{"width":1024,"height":1536,"url":"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/05\/muntatgesala2_151066949677_1024.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MuseuDali","twitter_misc":{"Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.salvador-dali.org\/es\/fundacion-dali\/noticia\/se-expone-figura-de-perfil\/","url":"https:\/\/www.salvador-dali.org\/es\/fundacion-dali\/noticia\/se-expone-figura-de-perfil\/","name":"Se expone Figura de perfil - Fundaci\u00f3 Gala - Salvador Dal\u00ed","isPartOf":{"@id":"https:\/\/www.salvador-dali.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salvador-dali.org\/es\/fundacion-dali\/noticia\/se-expone-figura-de-perfil\/#primaryimage"},"image":{"@id":"https:\/\/www.salvador-dali.org\/es\/fundacion-dali\/noticia\/se-expone-figura-de-perfil\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/05\/muntatgesala2_151066949677_1024.jpg","datePublished":"2017-11-12T22:00:00+00:00","dateModified":"2025-06-26T08:11:24+00:00","breadcrumb":{"@id":"https:\/\/www.salvador-dali.org\/es\/fundacion-dali\/noticia\/se-expone-figura-de-perfil\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salvador-dali.org\/es\/fundacion-dali\/noticia\/se-expone-figura-de-perfil\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.salvador-dali.org\/es\/fundacion-dali\/noticia\/se-expone-figura-de-perfil\/#primaryimage","url":"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/05\/muntatgesala2_151066949677_1024.jpg","contentUrl":"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/05\/muntatgesala2_151066949677_1024.jpg","width":1024,"height":1536,"caption":"Figura de perfil"},{"@type":"BreadcrumbList","@id":"https:\/\/www.salvador-dali.org\/es\/fundacion-dali\/noticia\/se-expone-figura-de-perfil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.salvador-dali.org\/es\/"},{"@type":"ListItem","position":2,"name":"Se expone Figura de perfil"}]},{"@type":"WebSite","@id":"https:\/\/www.salvador-dali.org\/es\/#website","url":"https:\/\/www.salvador-dali.org\/es\/","name":"Fundaci\u00f3 Gala - Salvador Dal\u00ed","description":"","publisher":{"@id":"https:\/\/www.salvador-dali.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salvador-dali.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.salvador-dali.org\/es\/#organization","name":"Fundaci\u00f3 Gala - Salvador Dal\u00ed","url":"https:\/\/www.salvador-dali.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.salvador-dali.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/04\/fundacio-gala-salvador-dali.png","contentUrl":"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/04\/fundacio-gala-salvador-dali.png","width":240,"height":240,"caption":"Fundaci\u00f3 Gala - Salvador Dal\u00ed"},"image":{"@id":"https:\/\/www.salvador-dali.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MuseusDali","https:\/\/x.com\/MuseuDali","https:\/\/www.youtube.com\/user\/FundacioDali","https:\/\/www.flickr.com\/fundacio_dali\/","https:\/\/instagram.com\/museudali"]}]}},"_links":{"self":[{"href":"https:\/\/www.salvador-dali.org\/es\/wp-json\/wp\/v2\/noticia\/8804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salvador-dali.org\/es\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/www.salvador-dali.org\/es\/wp-json\/wp\/v2\/types\/noticia"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salvador-dali.org\/es\/wp-json\/wp\/v2\/media\/5396"}],"wp:attachment":[{"href":"https:\/\/www.salvador-dali.org\/es\/wp-json\/wp\/v2\/media?parent=8804"}],"wp:term":[{"taxonomy":"categoria-actualitat","embeddable":true,"href":"https:\/\/www.salvador-dali.org\/es\/wp-json\/wp\/v2\/categoria-actualitat?post=8804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}