{"id":13224,"date":"2015-07-15T19:22:01","date_gmt":"2015-07-15T17:22:01","guid":{"rendered":"https:\/\/www.salvador-dali.org\/obra\/ced\/textos-en-descarrega\/dali-i-la-formiga-cara-a-cara-amb-l-esser-superior\/"},"modified":"2025-07-15T20:23:44","modified_gmt":"2025-07-15T18:23:44","slug":"dali-et-la-fourmi-face-a-face-avec-l-etre-supreme","status":"publish","type":"textos-en-descarrega","link":"https:\/\/www.salvador-dali.org\/fr\/oeuvre\/ced\/textes-en-telechargement\/dali-et-la-fourmi-face-a-face-avec-l-etre-supreme\/","title":{"rendered":"Dal\u00ed et la fourmi : face \u00e0 face avec l\u2019\u00eatre supr\u00eame"},"content":{"rendered":"<p>Parler de Salvador Dal\u00ed et des animaux revient \u00e0 parler de l&rsquo;un des \u00e9l\u00e9ments iconographiques majeurs de son \u0153uvre, comme on l&rsquo;observe d\u00e9j\u00e0 dans une de ses premi\u00e8res peintures, r\u00e9alis\u00e9e en 1915, alors qu&rsquo;il n&rsquo;avait que onze ans. Si chats, chiens, oiseaux et poissons entrent dans les compositions de l&rsquo;artiste, d&rsquo;autres animaux plus exotiques y figurent aussi, notamment les \u00e9l\u00e9phants ou les rhinoc\u00e9ros, sans oublier les insectes\u00a0: criquets, mouches et fourmis. Tous r\u00e9appara\u00eetront profus\u00e9ment dans son \u0153uvre, chacun avec son symbolisme particulier.<\/p>\n<p>Sur sa toile de fond artistique, de la fin des ann\u00e9es vingt jusqu&rsquo;\u00e0 la fin, ou presque, de sa trajectoire artistique, on rencontre la fourmi, un des animaux que Dal\u00ed admirera le plus. Nous avons donc choisi de nous arr\u00eater plus particuli\u00e8rement sur cet animal, toujours trait\u00e9 avec la plus grande insistance par le peintre, que l&rsquo;insecte fascinait.<\/p>\n<p>Salvador Dal\u00ed adh\u00e8re au groupe surr\u00e9aliste en 1929\u00a0; le surr\u00e9alisme \u00e9tait un mouvement compos\u00e9 principalement d&rsquo;\u00e9crivains, mais, avec le temps, des peintres et des sculpteurs le rejoignirent aussi. La fourmi figure dans nombre d&rsquo;\u0153uvres daliniennes de cette \u00e9poque\u00a0: <em>Le jeu lugubre<\/em>,<em> Le grand masturbateur<\/em>,<em> Les accommodations des d\u00e9sirs<\/em>,<em> Gala<\/em>,<em> La persistance de la m\u00e9moire <\/em>ou<em> Composition surr\u00e9aliste avec personnages invisibles<\/em>.<a href=\"#_edn1\" name=\"_ednref1\" title=\"\">[i]<\/a><\/p>\n<p>Le symbolisme qui baigne l&rsquo;\u0153uvre du peintre n&rsquo;est pas simple. Dans l&rsquo;huile <em>Le grand masturbateur<\/em>, Dal\u00ed recourt aux fourmis pour nous d\u00e9couvrir ses d\u00e9sirs et, en m\u00eame temps, les horreurs qui le tourmentent\u00a0: la fourmi est la repr\u00e9sentation de cette putr\u00e9faction qu&rsquo;il craint tant. Dans son autobiographie <em>La vie secr\u00e8te de Salvador Dal\u00ed<\/em>, publi\u00e9e en 1942, il nous donne des pistes pour comprendre le m\u00e9lange d&rsquo;attraction et de r\u00e9pulsion que lui inspire cet insecte\u00a0:<\/p>\n<p style=\"margin-left:35.4pt;\">[&#8230;] Le matin suivant, un spectacle affreux m&rsquo;attendait : \u00e0 peine arriv\u00e9 derri\u00e8re le lavoir, je trouve le verre renvers\u00e9, les coccinelles parties et la chauve-souris encore \u00e0 moiti\u00e9 vivante, mais h\u00e9riss\u00e9e des fourmis fr\u00e9n\u00e9tiques, son petit visage fr\u00e9missant montrant des dents de vieille. [&#8230;]<\/p>\n<p style=\"margin-left:35.4pt;\">D&rsquo;un geste \u00e9clair je ramasse la chauve-souris fourmillante que je porte vers ma bouche, pris de piti\u00e9 insurmontable [&#8230;]<a href=\"#_edn2\" name=\"_ednref2\" title=\"\">[ii]<\/a><\/p>\n<p>La m\u00eame ann\u00e9e, les fourmis apparaissent dans une autre \u0153uvre importante de Dal\u00ed. Il s&rsquo;agit d&rsquo;<em>Un Chien andalou<\/em>, un des deux films que le peintre a r\u00e9alis\u00e9s avec son grand ami de la Residencia de Estudiantes de Madrid, le cin\u00e9aste Luis Bu\u00f1uel. Dans son autobiographie, ce dernier \u00e9voque certaines sc\u00e8nes frappantes du film\u00a0:<\/p>\n<p style=\"margin-left:35.4pt;\">[&#8230;] Ce film naquit de la rencontre de deux r\u00eaves. En arrivant chez Dal\u00ed, \u00e0 Figueres, invit\u00e9 \u00e0 passer quelques jours, je lui racontai que j&rsquo;avais r\u00eav\u00e9, peu de temps auparavant, d&rsquo;un nuage effil\u00e9 coupant la lune et d&rsquo;une lame de rasoir fendant un \u0153il. De son c\u00f4t\u00e9 il me raconta qu&rsquo;il venait de voir en r\u00eave, la nuit pr\u00e9c\u00e9dente, une main pleine de fourmis. Il ajouta\u00a0: \u00abEt si nous faisions un film, en partant de \u00e7a\u00a0?\u00a0\u00bb. [&#8230;]<a href=\"#_edn3\" name=\"_ednref3\" title=\"\">[iii]<\/a><\/p>\n<p>Dans un article publi\u00e9 dans <em>La Publicitat<\/em><a href=\"#_edn4\" name=\"_ednref4\" title=\"\">[iv]<\/a> du 7 de mai 1929, Dal\u00ed explique ce qui suit\u00a0:<\/p>\n<p style=\"margin-left:35.4pt;\">[&#8230;] En ce qui concerne les fourmis, il est extr\u00eamement difficile de s&rsquo;en procurer \u00e0 Paris. Nous avons d\u00e9pens\u00e9 deux cents francs de taxi \u00e0 la recherche de fourmis, indispensables pour un film d&rsquo;avant-garde que nous r\u00e9alisions, Luis Bu\u00f1uel et moi, ces jours-ci, \u00e0 Paris [&#8230;].<\/p>\n<p>\u00c0 Paris, ils ne r\u00e9ussirent pas \u00e0 se procurer des fourmis pour le tournage et Bu\u00f1uel demanda \u00e0 Dal\u00ed de se les faire envoyer de Cadaqu\u00e9s. Finalement, les insectes arriv\u00e8rent \u00e0 Paris depuis la sierra de Guadarrama.<\/p>\n<p>La fourmi r\u00e9appara\u00eet dans un autre film, dans ce cas un court m\u00e9trage intitul\u00e9 <em>Destino<\/em>, coproduit par Walt Disney et Salvador Dal\u00ed en 1946. Bien que l&rsquo;original ne dure pas plus de deux minutes, les h\u00e9ritiers de Disney,\u00a0 en partant des dessins r\u00e9alis\u00e9s par ce dernier et par le peintre de l&rsquo;Empord\u00e0, ont\u00a0 compos\u00e9 un film bref o\u00f9 les fourmis ont \u00e0 nouveau leur place et se transforment avec fluidit\u00e9 en cyclistes, r\u00e9cup\u00e9rant\u00a0 l&rsquo;imaginaire bien connu d&rsquo;<em>Un Chien andalou<\/em>.<\/p>\n<p>En faisant un bond dans le temps, nous arrivons \u00e0 l&rsquo;huile Autoportrait mou au lard grill\u00e9,<a href=\"#_edn5\" name=\"_ednref5\" title=\"\"><strong><em><strong>[v]<\/strong><\/em><\/strong><\/a> de 1941. Dans cette \u0153uvre, Dal\u00ed cherche \u00e0 sugg\u00e9rer que l&rsquo;\u00e2me de l&rsquo;artiste manque d&rsquo;int\u00e9r\u00eat\u00a0; seul l&rsquo;ext\u00e9rieur signifie quelque chose\u00a0: sa peau molle et comestible. Les fourmis apparaissent sur son visage qui, tout comme l&rsquo;indique le titre, doit \u00e9galement \u00eatre mang\u00e9. Lors d&rsquo;un entretien r\u00e9alis\u00e9 la m\u00eame ann\u00e9e par Alfred Frankenstein,<a href=\"#_edn6\" name=\"_ednref6\" title=\"\"><strong><em><strong>[vi]<\/strong><\/em><\/strong><\/a> Dal\u00ed d\u00e9clare :<\/p>\n<p style=\"margin-left:35.4pt;\">[&#8230;] Autoportrait mou au lard grill\u00e9 repr\u00e9sente ma t\u00eate sans cr\u00e2ne pour la soutenir. [&#8230;] Le lard grill\u00e9 met l&rsquo;accent sur le caract\u00e8re consommable de la chair que les fourmis d\u00e9vorent. [&#8230;]<\/p>\n<p>Et, beaucoup plus tard, en 1959\u00a0: \u00ab\u00a0[&#8230;] je suis arriv\u00e9 \u00e0 la certitude que la fourmi est un \u00eatre sup\u00e9rieur. Pour bien conna\u00eetre quelque chose, il est n\u00e9cessaire d&rsquo;en manger, et ces fourmis mangent le temps. [&#8230;]\u00a0\u00bb.<a href=\"#_edn7\" name=\"_ednref7\" title=\"\">[vii]<\/a><\/p>\n<p>Tout au long de sa carri\u00e8re, Dal\u00ed revient \u00e0 plusieurs reprises sur l&rsquo;horreur que lui inspirent les fourmis, laquelle constitue un des moteurs cr\u00e9atifs importants de son \u0153uvre.<\/p>\n<p>Son adh\u00e9sion au groupe surr\u00e9aliste, en 1929, lui servira \u00e0 d\u00e9velopper pleinement sa cr\u00e9ativit\u00e9 et \u00e0 exprimer ses peurs et ses d\u00e9sirs &#8211;\u00a0en d\u00e9finitive, sa propre humanit\u00e9\u00a0&#8211; dans sa cr\u00e9ation artistique, en donnant vie \u00e0 des pi\u00e8ces qui, jour apr\u00e8s jour, sous la forme de peintures, d&rsquo;\u00e9crits ou de productions cin\u00e9matographiques, r\u00e9ussissent \u00e0 captiver le spectateur.<\/p>\n<p>Chaque \u0153uvre permet de se livrer \u00e0 une lecture plus attentive et de comprendre la libert\u00e9 avec laquelle Dal\u00ed con\u00e7oit la fourmi. Il s&rsquo;agit d&rsquo;observer l&rsquo;\u0153uvre, de l&rsquo;analyser et de la penser, mais dans la perspective dalinienne, libre et spectaculaire\u00a0; libre comme les fourmis cherchant leur chemin.<\/p>\n<p><strong>Fiona Mata <\/strong><\/p>\n<p><strong>Cuca R. Costa<\/strong><\/p>\n<p><strong>Centre d&rsquo;\u00e9tudes daliniennes<\/strong><\/p>\n<p><strong>Fundaci\u00f3 Gala-Salvador Dal\u00ed<\/strong><\/p>\n<hr\/>\n<div id=\"edn1\">\n<p><a href=\"#_ednref1\" name=\"_edn1\" title=\"\">[i]<\/a> Les \u0153uvres de Dal\u00ed cit\u00e9es dans cette publication sont accompagn\u00e9es du num\u00e9ro qu&rsquo;elles portent au catalogue raisonn\u00e9 de Salvador Dal\u00ed, consultable sur \/cataleg_raonat\/. <em>Le jeu lugubre<\/em>, 1929, collection priv\u00e9e, n\u00ba cat. 232\u00a0; <em>Les accommodations des d\u00e9sirs<\/em><em>, <\/em>1929, The Metropolitan Museum of Art, New York, n\u00ba cat. 239\u00a0; <em>Le grand masturbateur<\/em>, 1929, Museo Nacional Centro de Arte Reina Sof\u00eda, Madrid, n\u00ba cat. 235\u00a0; <em>Gala<\/em>, 1931, Fundaci\u00f3 Gala-Salvador Dal\u00ed, Figueres, n\u00ba cat. 278\u00a0; <em>La persistance de la m\u00e9moire<\/em>, 1931, The Museum of Modern Art, New York, n\u00ba cat. 265\u00a0; <em>Composition surr\u00e9aliste avec personnages invisibles<\/em><em>, 1936, <\/em>Fundaci\u00f3 Gala-Salvador Dal\u00ed, Figueres, n\u00ba cat. 420.<\/p>\n<div id=\"edn2\">\n<p><a href=\"#_ednref2\" name=\"_edn2\" title=\"\">[ii]<\/a> Dal\u00ed, Salvador. <em>La Vie secr\u00e8te de Salvador Dal\u00ed,<\/em> La Table Ronde, 1952, Paris, p. 15.<\/p>\n<div id=\"edn3\">\n<p><a href=\"#_ednref3\" name=\"_edn3\" title=\"\">[iii]<\/a> Bu\u00f1uel, Luis. <em>Mon dernier soupir<\/em>, Robert Laffont, Ramsay Poche Cin\u00e9ma, Paris, 1982, p. 125.<\/p>\n<div id=\"edn4\">\n<p><a href=\"#_ednref4\" name=\"_edn4\" title=\"\">[iv]<\/a> Dal\u00ed, Salvador. \u00ab\u00a0Documental-Par\u00eds-1929\u00a0\u00bb, <em>La Publicitat<\/em>, 07\/05\/1929, Barcelone.<\/p>\n<div id=\"edn5\">\n<p><a href=\"#_ednref5\" name=\"_edn5\" title=\"\">[v]<\/a> <em>Autoportrait mou au lard grill\u00e9<\/em>, 1941, Fundaci\u00f3 Gala-Salvador Dal\u00ed, Figueres, n\u00ba cat. 505.<\/p>\n<div id=\"edn6\">\n<p><a href=\"#_ednref6\" name=\"_edn6\" title=\"\">[vi]<\/a> Frankenstein, Alfred. \u00abUna visita a las galer\u00edas de arte. El artista Dal\u00ed posa para un retrato\u00bb, <em>San Francisco Chronicle, <\/em>24\/08\/1941, San Francisco, CA. In: <em>Obra completa<\/em>, vol. VII, <em>Entrevistas<\/em>. Destino, Fundaci\u00f3 Gala-Salvador Dal\u00ed, Sociedad Estatal de Conmemoraciones Culturales, Barcelone, Figueres, Madrid, 2006, p. 75.<\/p>\n<div id=\"edn7\">\n<p><a href=\"#_ednref7\" name=\"_edn7\" title=\"\">[vii]<\/a> Dal\u00ed, Salvador; Men\u00e9ndez-Chac\u00f3n, Manuel. \u00ab\u00a0Dal\u00ed, ese desconocido vecino de Portlligat\u00a0\u00bb, <em>Blanco y Negro<\/em>, 22\/08\/1959, Madrid<em>. <\/em>En: <em>Obra completa<\/em>, vol. VII, <em>Entrevistas<\/em>, Destino, Fundaci\u00f3 Gala-Salvador Dal\u00ed, Sociedad Estatal de Conmemoraciones Culturales<em>, <\/em>Barcelone, Figueres, Madrid, 2006, p. 740.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Parler de Salvador Dal\u00ed et des animaux revient \u00e0 parler de l&rsquo;un des \u00e9l\u00e9ments iconographiques majeurs de son \u0153uvre, comme on l&rsquo;observe d\u00e9j\u00e0 dans une de ses premi\u00e8res peintures, r\u00e9alis\u00e9e en 1915, alors qu&rsquo;il n&rsquo;avait que onze ans. Si chats, chiens, oiseaux et poissons entrent dans les compositions de l&rsquo;artiste, d&rsquo;autres animaux plus exotiques y [&hellip;]<\/p>\n","protected":false},"featured_media":13063,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false,"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":""},"class_list":["post-13224","textos-en-descarrega","type-textos-en-descarrega","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dal\u00ed et la fourmi : face \u00e0 face avec l\u2019\u00eatre supr\u00eame - Fundaci\u00f3 Gala - Salvador Dal\u00ed<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salvador-dali.org\/fr\/oeuvre\/ced\/textes-en-telechargement\/dali-et-la-fourmi-face-a-face-avec-l-etre-supreme\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dal\u00ed et la fourmi : face \u00e0 face avec l\u2019\u00eatre supr\u00eame - Fundaci\u00f3 Gala - Salvador Dal\u00ed\" \/>\n<meta property=\"og:description\" content=\"Parler de Salvador Dal\u00ed et des animaux revient \u00e0 parler de l&rsquo;un des \u00e9l\u00e9ments iconographiques majeurs de son \u0153uvre, comme on l&rsquo;observe d\u00e9j\u00e0 dans une de ses premi\u00e8res peintures, r\u00e9alis\u00e9e en 1915, alors qu&rsquo;il n&rsquo;avait que onze ans. Si chats, chiens, oiseaux et poissons entrent dans les compositions de l&rsquo;artiste, d&rsquo;autres animaux plus exotiques y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salvador-dali.org\/fr\/oeuvre\/ced\/textes-en-telechargement\/dali-et-la-fourmi-face-a-face-avec-l-etre-supreme\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3 Gala - Salvador Dal\u00ed\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MuseusDali\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-15T18:23:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/07\/autoretrat_tou_1460037344_1024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"276\" \/>\n\t<meta property=\"og:image:height\" content=\"329\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MuseuDali\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/fr\\\/oeuvre\\\/ced\\\/textes-en-telechargement\\\/dali-et-la-fourmi-face-a-face-avec-l-etre-supreme\\\/\",\"url\":\"https:\\\/\\\/www.salvador-dali.org\\\/fr\\\/oeuvre\\\/ced\\\/textes-en-telechargement\\\/dali-et-la-fourmi-face-a-face-avec-l-etre-supreme\\\/\",\"name\":\"Dal\u00ed et la fourmi : face \u00e0 face avec l\u2019\u00eatre supr\u00eame - Fundaci\u00f3 Gala - Salvador Dal\u00ed\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/fr\\\/oeuvre\\\/ced\\\/textes-en-telechargement\\\/dali-et-la-fourmi-face-a-face-avec-l-etre-supreme\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/fr\\\/oeuvre\\\/ced\\\/textes-en-telechargement\\\/dali-et-la-fourmi-face-a-face-avec-l-etre-supreme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.salvador-dali.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/autoretrat_tou_1460037344_1024.jpg\",\"datePublished\":\"2015-07-15T17:22:01+00:00\",\"dateModified\":\"2025-07-15T18:23:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/fr\\\/oeuvre\\\/ced\\\/textes-en-telechargement\\\/dali-et-la-fourmi-face-a-face-avec-l-etre-supreme\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.salvador-dali.org\\\/fr\\\/oeuvre\\\/ced\\\/textes-en-telechargement\\\/dali-et-la-fourmi-face-a-face-avec-l-etre-supreme\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/fr\\\/oeuvre\\\/ced\\\/textes-en-telechargement\\\/dali-et-la-fourmi-face-a-face-avec-l-etre-supreme\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.salvador-dali.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/autoretrat_tou_1460037344_1024.jpg\",\"contentUrl\":\"https:\\\/\\\/www.salvador-dali.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/autoretrat_tou_1460037344_1024.jpg\",\"width\":276,\"height\":329,\"caption\":\"Dal\u00ed i la formiga: cara a cara amb l'\u00e9sser superior\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/fr\\\/oeuvre\\\/ced\\\/textes-en-telechargement\\\/dali-et-la-fourmi-face-a-face-avec-l-etre-supreme\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.salvador-dali.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dal\u00ed et la fourmi : face \u00e0 face avec l\u2019\u00eatre supr\u00eame\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.salvador-dali.org\\\/fr\\\/\",\"name\":\"Fundaci\u00f3 Gala - Salvador Dal\u00ed\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.salvador-dali.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/fr\\\/#organization\",\"name\":\"Fundaci\u00f3 Gala - Salvador Dal\u00ed\",\"url\":\"https:\\\/\\\/www.salvador-dali.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.salvador-dali.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/fundacio-gala-salvador-dali.png\",\"contentUrl\":\"https:\\\/\\\/www.salvador-dali.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/fundacio-gala-salvador-dali.png\",\"width\":240,\"height\":240,\"caption\":\"Fundaci\u00f3 Gala - Salvador Dal\u00ed\"},\"image\":{\"@id\":\"https:\\\/\\\/www.salvador-dali.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MuseusDali\",\"https:\\\/\\\/x.com\\\/MuseuDali\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/FundacioDali\",\"https:\\\/\\\/www.flickr.com\\\/fundacio_dali\\\/\",\"https:\\\/\\\/instagram.com\\\/museudali\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dal\u00ed et la fourmi : face \u00e0 face avec l\u2019\u00eatre supr\u00eame - Fundaci\u00f3 Gala - Salvador Dal\u00ed","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salvador-dali.org\/fr\/oeuvre\/ced\/textes-en-telechargement\/dali-et-la-fourmi-face-a-face-avec-l-etre-supreme\/","og_locale":"fr_FR","og_type":"article","og_title":"Dal\u00ed et la fourmi : face \u00e0 face avec l\u2019\u00eatre supr\u00eame - Fundaci\u00f3 Gala - Salvador Dal\u00ed","og_description":"Parler de Salvador Dal\u00ed et des animaux revient \u00e0 parler de l&rsquo;un des \u00e9l\u00e9ments iconographiques majeurs de son \u0153uvre, comme on l&rsquo;observe d\u00e9j\u00e0 dans une de ses premi\u00e8res peintures, r\u00e9alis\u00e9e en 1915, alors qu&rsquo;il n&rsquo;avait que onze ans. Si chats, chiens, oiseaux et poissons entrent dans les compositions de l&rsquo;artiste, d&rsquo;autres animaux plus exotiques y [&hellip;]","og_url":"https:\/\/www.salvador-dali.org\/fr\/oeuvre\/ced\/textes-en-telechargement\/dali-et-la-fourmi-face-a-face-avec-l-etre-supreme\/","og_site_name":"Fundaci\u00f3 Gala - Salvador Dal\u00ed","article_publisher":"https:\/\/www.facebook.com\/MuseusDali","article_modified_time":"2025-07-15T18:23:44+00:00","og_image":[{"width":276,"height":329,"url":"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/07\/autoretrat_tou_1460037344_1024.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MuseuDali","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.salvador-dali.org\/fr\/oeuvre\/ced\/textes-en-telechargement\/dali-et-la-fourmi-face-a-face-avec-l-etre-supreme\/","url":"https:\/\/www.salvador-dali.org\/fr\/oeuvre\/ced\/textes-en-telechargement\/dali-et-la-fourmi-face-a-face-avec-l-etre-supreme\/","name":"Dal\u00ed et la fourmi : face \u00e0 face avec l\u2019\u00eatre supr\u00eame - Fundaci\u00f3 Gala - Salvador Dal\u00ed","isPartOf":{"@id":"https:\/\/www.salvador-dali.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.salvador-dali.org\/fr\/oeuvre\/ced\/textes-en-telechargement\/dali-et-la-fourmi-face-a-face-avec-l-etre-supreme\/#primaryimage"},"image":{"@id":"https:\/\/www.salvador-dali.org\/fr\/oeuvre\/ced\/textes-en-telechargement\/dali-et-la-fourmi-face-a-face-avec-l-etre-supreme\/#primaryimage"},"thumbnailUrl":"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/07\/autoretrat_tou_1460037344_1024.jpg","datePublished":"2015-07-15T17:22:01+00:00","dateModified":"2025-07-15T18:23:44+00:00","breadcrumb":{"@id":"https:\/\/www.salvador-dali.org\/fr\/oeuvre\/ced\/textes-en-telechargement\/dali-et-la-fourmi-face-a-face-avec-l-etre-supreme\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salvador-dali.org\/fr\/oeuvre\/ced\/textes-en-telechargement\/dali-et-la-fourmi-face-a-face-avec-l-etre-supreme\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.salvador-dali.org\/fr\/oeuvre\/ced\/textes-en-telechargement\/dali-et-la-fourmi-face-a-face-avec-l-etre-supreme\/#primaryimage","url":"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/07\/autoretrat_tou_1460037344_1024.jpg","contentUrl":"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/07\/autoretrat_tou_1460037344_1024.jpg","width":276,"height":329,"caption":"Dal\u00ed i la formiga: cara a cara amb l'\u00e9sser superior"},{"@type":"BreadcrumbList","@id":"https:\/\/www.salvador-dali.org\/fr\/oeuvre\/ced\/textes-en-telechargement\/dali-et-la-fourmi-face-a-face-avec-l-etre-supreme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.salvador-dali.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Dal\u00ed et la fourmi : face \u00e0 face avec l\u2019\u00eatre supr\u00eame"}]},{"@type":"WebSite","@id":"https:\/\/www.salvador-dali.org\/fr\/#website","url":"https:\/\/www.salvador-dali.org\/fr\/","name":"Fundaci\u00f3 Gala - Salvador Dal\u00ed","description":"","publisher":{"@id":"https:\/\/www.salvador-dali.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salvador-dali.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.salvador-dali.org\/fr\/#organization","name":"Fundaci\u00f3 Gala - Salvador Dal\u00ed","url":"https:\/\/www.salvador-dali.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.salvador-dali.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/04\/fundacio-gala-salvador-dali.png","contentUrl":"https:\/\/www.salvador-dali.org\/wp-content\/uploads\/2025\/04\/fundacio-gala-salvador-dali.png","width":240,"height":240,"caption":"Fundaci\u00f3 Gala - Salvador Dal\u00ed"},"image":{"@id":"https:\/\/www.salvador-dali.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MuseusDali","https:\/\/x.com\/MuseuDali","https:\/\/www.youtube.com\/user\/FundacioDali","https:\/\/www.flickr.com\/fundacio_dali\/","https:\/\/instagram.com\/museudali"]}]}},"_links":{"self":[{"href":"https:\/\/www.salvador-dali.org\/fr\/wp-json\/wp\/v2\/textos-en-descarrega\/13224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.salvador-dali.org\/fr\/wp-json\/wp\/v2\/textos-en-descarrega"}],"about":[{"href":"https:\/\/www.salvador-dali.org\/fr\/wp-json\/wp\/v2\/types\/textos-en-descarrega"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.salvador-dali.org\/fr\/wp-json\/wp\/v2\/media\/13063"}],"wp:attachment":[{"href":"https:\/\/www.salvador-dali.org\/fr\/wp-json\/wp\/v2\/media?parent=13224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}